{"id":8818,"date":"2021-12-17T15:35:19","date_gmt":"2021-12-17T14:35:19","guid":{"rendered":"https:\/\/www.brasseurs-air-re2020.com\/re2020-im-einfamilienhaus-arbeiten-die-dem-kunden-vorbehalten-sind-worauf-ist-zu-achten\/"},"modified":"2026-07-13T22:55:14","modified_gmt":"2026-07-13T20:55:14","slug":"re2020-im-einfamilienhaus-arbeiten-die-dem-kunden-vorbehalten-sind-worauf-ist-zu-achten","status":"publish","type":"post","link":"https:\/\/www.brasseurs-air-re2020.com\/de\/re2020-im-einfamilienhaus-arbeiten-die-dem-kunden-vorbehalten-sind-worauf-ist-zu-achten\/","title":{"rendered":"RE2020 im Einfamilienhaus: Arbeiten, die dem Kunden vorbehalten sind, worauf ist zu achten?"},"content":{"rendered":"<div class=\"pdfprnt-buttons pdfprnt-buttons-post pdfprnt-top-right\"><a href=\"javascript: imageToPdf()\" class=\"pdfprnt-button pdfprnt-button-pdf\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.brasseurs-air-re2020.com\/wp-content\/plugins\/pdf-print\/images\/pdf.png\" alt=\"image_pdf\" title=\"PDF anzeigen\" \/><span class=\"pdfprnt-button-title pdfprnt-button-pdf-title\">T\u00e9l\u00e9charger l\u2019article en PDF<\/span><\/a><\/div><p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text ul_item_indent=&#8221;25px&#8221; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; header_4_font_size=&#8221;16px&#8221; background_color=&#8221;#d4f0fc&#8221; custom_padding=&#8221;20px|20px|20px|20px|true|true&#8221; box_shadow_style=&#8221;preset2&#8243; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4>Hitzewelle 2003: Tausende Tote und langfristige Auswirkungen<\/h4>\n<p>[\/et_pb_text][et_pb_text ul_item_indent=&#8221;25px&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; header_3_font=&#8221;|600|||||||&#8221; header_3_text_color=&#8221;gcid-70ff693f-6f97-4074-be90-9adb196c4afe&#8221; header_4_font=&#8221;|600|||||||&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{%22gcid-70ff693f-6f97-4074-be90-9adb196c4afe%22:%91%22header_3_text_color%22%93}&#8221;]<\/p>\n<p>Der Vertrag \u00fcber den Bau eines Einfamilienhauses unterliegt einem besonderen Rahmen, <a href=\"https:\/\/www.economie.gouv.fr\/files\/files\/directions_services\/dgccrf\/documentation\/fiches_pratiques\/fiches\/contrat-construction-maison-individuelle.pdf\" target=\"_blank\" rel=\"noopener\">der den Verbraucher sch\u00fctzt<\/a>.<\/p>\n<p><\/p>\n<p>Der Preis des zu bauenden Hauses, der im Vertrag genannt wird, setzt sich zwingend aus den Kosten des Geb\u00e4udes zusammen, die der Summe des vereinbarten Preises und gegebenenfalls den Kosten der Arbeiten, deren Ausf\u00fchrung sich der Bauherr vorbeh\u00e4lt, entsprechen<a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a>. Diese Arbeiten, f\u00fcr die der K\u00e4ufer aufkommen muss, werden als &#8220;vorbehaltene Arbeiten&#8221; bezeichnet.<\/p>\n<p><\/p>\n<p>Wenn sie Teil des Projekts sind, muss der Bauherr daher unbedingt die entsprechenden <strong>Kosten f\u00fcr die Deckenventilatoren in seinem Preis ausweisen<\/strong>.<\/p>\n<p><\/p>\n<p>Dies ist umso wichtiger, als das Bau- und Wohnungsgesetzbuch (CCH) vorsieht, dass der Bauherr verpflichtet ist, die vorbehaltenen Arbeiten zu den im Vertrag genannten Preisen und Bedingungen auszuf\u00fchren oder ausf\u00fchren zu lassen, wenn der Bauherr ihn innerhalb von vier Monaten nach Vertragsunterzeichnung dazu auffordert.<a href=\"#_ftn2\" name=\"_ftnref2\">[2]<\/a>.<\/p>\n<p><\/p>\n<p>Kurz gesagt, die vorbehaltenen Arbeiten, die in dem dem Vertrag beigef\u00fcgten Merkblatt erscheinen, m\u00fcssen also <strong>sehr genau beziffert werden<\/strong><\/p>\n<p><\/p>\n<p>Der Kassationshof hat \u00fcbrigens 2019 einem Bauherrn gegen einen Bauunternehmer Recht gegeben, dessen Vertrag die vorbehaltenen Arbeiten nicht genau genug bezifferte.<a href=\"#_ftn3\" name=\"_ftnref3\">[3]<\/a>.<\/p>\n<p>[\/et_pb_text][et_pb_text ul_item_indent=&#8221;25px&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;|600|||||||&#8221; header_2_text_color=&#8221;gcid-70ff693f-6f97-4074-be90-9adb196c4afe&#8221; header_2_font_size=&#8221;22px&#8221; header_3_font=&#8221;|600|||||||&#8221; header_3_text_color=&#8221;gcid-70ff693f-6f97-4074-be90-9adb196c4afe&#8221; header_4_font=&#8221;|600|||||||&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{%22gcid-70ff693f-6f97-4074-be90-9adb196c4afe%22:%91%22header_3_text_color%22,%22header_2_text_color%22%93}&#8221;]<\/p>\n<h2>Welche Verantwortung tr\u00e4gt der Bauherr?<\/h2>\n<p><\/p>\n<p>Im Rahmen der RE2020, der Energie- und Umweltvorschriften, ist der Bauherr verpflichtet, im Rahmen seines Bauantrags eine Bescheinigung \u00fcber die Ber\u00fccksichtigung der Anforderungen an die Energie- und Umweltleistung zu erstellen.<\/p>\n<p><\/p>\n<p>Diese Erstbescheinigung erfordert die Durchf\u00fchrung einer Energie- und Umweltstudie, deren Leitung wahrscheinlich dem Bauherrn obliegen wird.<\/p>\n<p><\/p>\n<p>Nach Abschluss der Bauarbeiten muss der Bauherr bei der Fertigstellung des Geb\u00e4udes eine zweite Bescheinigung \u00fcber die Ber\u00fccksichtigung der Anforderungen an die Energieeffizienz und die Umweltvertr\u00e4glichkeit ausstellen.<\/p>\n<p><\/p>\n<p>Diese letzte Bescheinigung wird wahrscheinlich erneut vom Bauunternehmer in <strong>\u00dcbereinstimmung mit dem Merkblatt, in dem die vorbehaltenen Arbeiten beschrieben werden<\/strong>, erstellt.<\/p>\n<p><\/p>\n<p>Stellen wir uns nun vor, dass der Bauherr aus Kostengr\u00fcnden im Rahmen der gebuchten Arbeiten Produkte w\u00e4hlt, die sich vom Merkblatt unterscheiden und weniger leistungsf\u00e4hig sind als die in der Studie erw\u00e4hnten.<\/p>\n<p><\/p>\n<p>Wenn bei der Kontrolle die Bescheinigung des Bauherrn abgelehnt wird, kann er sich nicht an den Hersteller wenden, <strong>sondern muss die gesamte nicht konforme Anlage auf eigene Kosten austauschen<\/strong>.<\/p>\n<p><\/p>\n<p>Die Nichterteilung der beh\u00f6rdlichen Genehmigung ist n\u00e4mlich Teil der <strong>aufschiebenden Bedingungen<\/strong> der meisten Vertr\u00e4ge \u00fcber den Bau eines Einfamilienhauses.<\/p>\n<p><\/p>\n<p>Die aufl\u00f6senden Bedingungen bewirken jedoch, dass der Vertrag zu Lasten des Bauherrn gek\u00fcndigt wird, wenn die Nichterf\u00fcllung einer aufschiebenden Bedingung dem Bauherrn zuzuschreiben ist.<a href=\"#_ftn4\" name=\"_ftnref4\">[4]<\/a>.<\/p>\n<p><\/p>\n<p>So kann der Bauherr in der Situation, dass die dem Bauherrn vorbehaltenen Arbeiten nicht mit der thermischen Studie \u00fcbereinstimmen, ernsthaft bestraft werden.<\/p>\n<p>[\/et_pb_text][et_pb_text ul_item_indent=&#8221;25px&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; header_3_font=&#8221;|600|||||||&#8221; header_3_text_color=&#8221;gcid-70ff693f-6f97-4074-be90-9adb196c4afe&#8221; header_4_font=&#8221;|600|||||||&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{%22gcid-70ff693f-6f97-4074-be90-9adb196c4afe%22:%91%22header_3_text_color%22%93}&#8221;]<\/p>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> Siehe <a href=\"https:\/\/www.legifrance.gouv.fr\/codes\/article_lc\/LEGIARTI000038433496\/\" target=\"_blank\" rel=\"noopener\">Artikel L231-2 des Code de la Construction et de l&#8217;Habitation (Bau- und Wohngesetzbuch)<\/a> <br \/><a href=\"#_ftnref2\" name=\"_ftn2\">[2]<\/a> Siehe\u00a0<a href=\"https:\/\/www.legifrance.gouv.fr\/codes\/article_lc\/LEGIARTI000006824498\" target=\"_blank\" rel=\"noopener\">Artikel L231-7 des CCH<\/a> <br \/><a href=\"#_ftnref3\" name=\"_ftn3\">[3]<\/a> Siehe <a href=\"https:\/\/www.onb-france.com\/actualites\/la-description-et-le-chiffrage-des-travaux-demeurant-la-charge-du-maitre-de-louvrage\" target=\"_blank\" rel=\"noopener\">Referenzen der Entscheidung<\/a> <br \/><a href=\"#_ftnref4\" name=\"_ftn4\">[4]<\/a> Gem\u00e4\u00df <a href=\"https:\/\/www.legifrance.gouv.fr\/codes\/article_lc\/LEGIARTI000032041243\" target=\"_blank\" rel=\"noopener\">Artikel 1178 des Zivilgesetzbuches<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text ul_item_indent=&#8221;25px&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;|600|||||||&#8221; header_2_text_color=&#8221;gcid-70ff693f-6f97-4074-be90-9adb196c4afe&#8221; header_2_font_size=&#8221;22px&#8221; header_3_font=&#8221;||||||||&#8221; header_3_text_color=&#8221;gcid-70ff693f-6f97-4074-be90-9adb196c4afe&#8221; header_3_font_size=&#8221;20px&#8221; header_3_line_height=&#8221;1.7em&#8221; header_4_font=&#8221;|600|||||||&#8221; global_colors_info=&#8221;{%22gcid-70ff693f-6f97-4074-be90-9adb196c4afe%22:%91%22header_3_text_color%22,%22header_2_text_color%22,%22header_3_text_color%22%93}&#8221;]<\/p>\n<h2>Die Bescheinigung \u00fcber die Ber\u00fccksichtigung der Anforderungen an die Energieeffizienz und die Umweltvertr\u00e4glichkeit<\/h2>\n<p><\/p>\n<p>Die Bescheinigungen \u00fcber die Ber\u00fccksichtigung der Anforderungen an die Gesamtenergieeffizienz und die Umweltvertr\u00e4glichkeit in RE2020 erscheinen im <a href=\"https:\/\/www.legifrance.gouv.fr\/jorf\/id\/JORFTEXT000044388032\" target=\"_blank\" rel=\"noopener\">Dekret vom 30. November 2021<\/a> und im <a href=\"https:\/\/www.legifrance.gouv.fr\/jorf\/id\/JORFTEXT000044501420\" target=\"_blank\" rel=\"noopener\">Erlass vom 9. Dezember 2021<\/a>.<\/p>\n<p><\/p>\n<p>Der Text des Erlasses ist sehr klar: Er sieht vor, dass die Zusammenfassung der Energie- und Umweltstudie in elektronischer Form bereitgestellt wird, sowie die <strong>Dokumente, die die Mengen und Referenzen der in der Zusammenfassung aufgef\u00fchrten Produkte belegen<\/strong>.<\/p>\n<p><\/p>\n<p>Schlie\u00dflich wird in den Texten die Bedeutung der Einhaltung der Gradstunden des Unbehagens im Sommer hervorgehoben, ohne die das Geb\u00e4ude nicht den Anforderungen entspricht.<\/p>\n<p><\/p>\n<p>Es sei daran erinnert, dass Deckenventilatoren eine der wichtigsten Einrichtungen sind, die die Einhaltung des Kriteriums der Gradstunden erm\u00f6glichen.<\/p>\n<p><\/p>\n<p>Eine zugelassene Pr\u00fcfstelle wird die Bescheinigung vor Ort \u00fcberpr\u00fcfen und sicherstellen, dass die Beschreibung mit den tats\u00e4chlich eingebauten Materialien \u00fcbereinstimmt.<\/p>\n<p><\/p>\n<p>Um die Anforderungen der RE2020 an den Indikator DH (Grad-Stunden) f\u00fcr den Sommerkomfort zu erf\u00fcllen, <strong>ist es daher unerl\u00e4sslich, darauf zu achten, dass das am Tag des Besuchs des Kontrolleurs installierte Produkt mit der Studie \u00fcbereinstimmt!<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text ul_item_indent=&#8221;25px&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;|600|||||||&#8221; header_2_text_color=&#8221;gcid-70ff693f-6f97-4074-be90-9adb196c4afe&#8221; header_2_font_size=&#8221;22px&#8221; header_3_font=&#8221;||||||||&#8221; header_3_text_color=&#8221;gcid-70ff693f-6f97-4074-be90-9adb196c4afe&#8221; header_3_font_size=&#8221;20px&#8221; header_3_line_height=&#8221;1.7em&#8221; header_4_font=&#8221;|600|||||||&#8221; global_colors_info=&#8221;{%22gcid-70ff693f-6f97-4074-be90-9adb196c4afe%22:%91%22header_3_text_color%22,%22header_2_text_color%22,%22header_3_text_color%22,%22header_3_text_color%22%93}&#8221;]<\/p>\n<h2>Fertigstellungserkl\u00e4rung, Bankfinanzierung und Versicherungen<\/h2>\n<p><\/p>\n<p>Die Erkl\u00e4rung \u00fcber die Fertigstellung und Konformit\u00e4t der Bauarbeiten (D\u00e9claration attestant l&#8217;ach\u00e8vement et la conformit\u00e9 des travaux (DAACT)) muss bei der Stadtverwaltung des Bauortes eingereicht werden. Dieses Dokument, das die Bescheinigung \u00fcber die Ber\u00fccksichtigung der RE2020 enth\u00e4lt, ist obligatorisch und kann mit einer Geldstrafe von bis zu 300.000 \u20ac<a href=\"#_ftn5\" name=\"_ftnref5\">[5]<\/a> geahndet werden. Wird die Erkl\u00e4rung \u00fcber die Konformit\u00e4t der Bauarbeiten nicht abgegeben, kann der Inhaber der Genehmigung gegen\u00fcber Dritten haftbar gemacht werden. Dar\u00fcber hinaus werden auch die meisten Banken und Versicherungen dieses Dokument verlangen.<\/p>\n<p><\/p>\n<p>Die Banken ben\u00f6tigen es, um die betreffende Kredittranche freizugeben.<\/p>\n<p><\/p>\n<p>Die Versicherungsgesellschaften wiederum ben\u00f6tigen das Dokument im Rahmen der Bauschadensversicherung. Ohne dieses Dokument k\u00f6nnte der Bauherr im Schadensfall keine Entsch\u00e4digung erhalten.<\/p>\n<p>[\/et_pb_text][et_pb_text ul_item_indent=&#8221;25px&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; header_3_font=&#8221;||||||||&#8221; header_3_text_color=&#8221;gcid-70ff693f-6f97-4074-be90-9adb196c4afe&#8221; header_3_line_height=&#8221;1.7em&#8221; header_4_font=&#8221;|600|||||||&#8221; global_colors_info=&#8221;{%22gcid-70ff693f-6f97-4074-be90-9adb196c4afe%22:%91%22header_3_text_color%22%93}&#8221;]<\/p>\n<p><a href=\"#_ftnref5\" name=\"_ftn5\">[5]<\/a> <a href=\"https:\/\/www.legifrance.gouv.fr\/codes\/article_lc\/LEGIARTI000041411270\/\" target=\"_blank\" rel=\"noopener\">Artikel L480-4 des St\u00e4dtebaugesetzes<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text ul_item_indent=&#8221;25px&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; header_3_font=&#8221;|600|||||||&#8221; header_3_font_size=&#8221;20px&#8221; header_3_line_height=&#8221;1.7em&#8221; header_4_font=&#8221;|600|||||||&#8221; header_4_font_size=&#8221;20px&#8221; custom_padding=&#8221;20px|20px|20px|20px|false|false&#8221; border_width_all=&#8221;1px&#8221; global_colors_info=&#8221;{%22gcid-70ff693f-6f97-4074-be90-9adb196c4afe%22:%91%22header_3_text_color%22,%22header_3_text_color%22%93}&#8221;]<\/p>\n<h3>Last Minute: Sichtpr\u00fcfung der Luftsprudler f\u00fcr die Fertigstellungserkl\u00e4rung<\/h3>\n<p><\/p>\n<p><a href=\"https:\/\/www.legifrance.gouv.fr\/jorf\/article_jo\/JORFARTI000044501447\" target=\"_blank\" rel=\"noopener\">Artikel 7 des Erlasses vom 9. Dezember 2021<\/a> erw\u00e4hnt die <strong>visuelle Vor-Ort-Kontrolle<\/strong> der Generatoren f\u00fcr Heizung oder K\u00fchlung einerseits und f\u00fcr die Bel\u00fcftung andererseits.<\/p>\n<p><\/p>\n<p>Wir haben auf der Website RT-RE B\u00e2timent* gefragt, <strong>zu welcher Kategorie Deckenventilatoren geh\u00f6ren<\/strong>: K\u00fchlerzeuger oder L\u00fcftungssysteme.<\/p>\n<p><\/p>\n<p>Die Antwort, die wir am 27. Januar 2022 erhielten, lautete wie folgt:<\/p>\n<p><\/p>\n<p><em>&#8220;Der Begriff K\u00fchlung umfasst sowohl die aktive als auch die passive K\u00fchlung. Also geh\u00f6ren Deckenventilatoren und Klimasch\u00e4chte zu den ber\u00fccksichtigten Systemen, auch wenn sie nicht explizit erw\u00e4hnt werden.&#8221;<\/em><\/p>\n<p><\/p>\n<p><strong>So m\u00fcssen Deckenventilatoren, wie auch die \u00fcbrige Ausr\u00fcstung, bei der Besichtigung einer Sichtpr\u00fcfung unterzogen werden. <\/strong><\/p>\n<p><\/p>\n<p>* Herausgeber der Website ist die DHUP (Direction de l&#8217;Habitation, de l&#8217;Urbanisme et des Paysage), die den Ministerien f\u00fcr den \u00f6kologischen und solidarischen \u00dcbergang (MTES) und f\u00fcr den territorialen Zusammenhalt und die Beziehungen zu den Gebietsk\u00f6rperschaften (MCTRCT) angegliedert ist.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text ul_item_indent=&#8221;25px&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;|600|||||||&#8221; header_2_text_color=&#8221;gcid-70ff693f-6f97-4074-be90-9adb196c4afe&#8221; header_2_font_size=&#8221;22px&#8221; header_3_font=&#8221;||||||||&#8221; header_3_text_color=&#8221;gcid-70ff693f-6f97-4074-be90-9adb196c4afe&#8221; header_3_font_size=&#8221;20px&#8221; header_3_line_height=&#8221;1.7em&#8221; header_4_font=&#8221;|600|||||||&#8221; custom_margin=&#8221;||10px||false|false&#8221; custom_padding=&#8221;||||false|false&#8221; global_colors_info=&#8221;{%22gcid-70ff693f-6f97-4074-be90-9adb196c4afe%22:%91%22header_3_text_color%22,%22header_2_text_color%22,%22header_3_text_color%22,%22header_3_text_color%22%93}&#8221;]<\/p>\n<h2>Erinnerung an die Norm zur H\u00f6he unter den Rotorbl\u00e4ttern<\/h2>\n<p><\/p>\n<p>Schlie\u00dflich m\u00fcssen Deckenventilatoren gem\u00e4\u00df der <a href=\"https:\/\/www.boutique.afnor.org\/fr-fr\/norme\/nf-en-60335280\/appareils-electrodomestiques-et-analogues-securite-partie-280-regles-partic\/fa123935\/24008?pk_source=google-adwords&amp;pk_medium=cpc&amp;gclid=Cj0KCQiAqbyNBhC2ARIsALDwAsAVmITjdQiqIn8ZM6REIctVI9Fmhnh95J7htfU1Q_cf4gsbVxQD73UaAoHbEALw_wcB\" target=\"_blank\" rel=\"noopener\">Norm NF EN IEC 60335-2-80<\/a> so installiert werden, dass der Abstand zwischen dem Boden und den Fl\u00fcgeln mindestens 2,30 m betr\u00e4gt.<\/p>\n<p>Mit einer H\u00f6he zwischen 18 und 20 cm erf\u00fcllen die Luftumw\u00e4lzer an diesem Standort diese Bedingung bei einer Deckenh\u00f6he von 2,50 m.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text ul_item_indent=&#8221;25px&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;|600|||||||&#8221; header_2_text_color=&#8221;gcid-70ff693f-6f97-4074-be90-9adb196c4afe&#8221; header_2_font_size=&#8221;22px&#8221; header_3_font=&#8221;||||||||&#8221; header_3_text_color=&#8221;gcid-70ff693f-6f97-4074-be90-9adb196c4afe&#8221; header_3_font_size=&#8221;20px&#8221; header_3_line_height=&#8221;1.7em&#8221; header_4_font=&#8221;|600|||||||&#8221; global_colors_info=&#8221;{%22gcid-70ff693f-6f97-4074-be90-9adb196c4afe%22:%91%22header_3_text_color%22,%22header_2_text_color%22,%22header_3_text_color%22,%22header_3_text_color%22,%22header_3_text_color%22,%22header_3_text_color%22%93}&#8221;]<\/p>\n<h2>Beispiel f\u00fcr eine Beschreibung, die in die Anleitung aufgenommen werden soll<\/h2>\n<p><\/p>\n<p>Hier ist ein Beispiel f\u00fcr einen Text, der in der Anleitung zur Beschreibung der gebuchten Arbeiten enthalten sein muss, die dem Vertrag \u00fcber den Bau eines Einfamilienhauses beigef\u00fcgt ist.<\/p>\n<p>[\/et_pb_text][et_pb_text ul_position=&#8221;inside&#8221; ul_item_indent=&#8221;25px&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; header_3_font=&#8221;|600|||||||&#8221; header_3_font_size=&#8221;20px&#8221; header_3_line_height=&#8221;1.7em&#8221; header_4_font=&#8221;|600|||||||&#8221; custom_padding=&#8221;20px|20px|20px|20px|true|true&#8221; border_width_all=&#8221;1px&#8221; global_colors_info=&#8221;{%22gcid-70ff693f-6f97-4074-be90-9adb196c4afe%22:%91%22header_3_text_color%22,%22header_3_text_color%22,%22header_3_text_color%22,%22header_3_text_color%22,%22header_3_text_color%22,%22header_3_text_color%22%93}&#8221;]<\/p>\n<h3>Exhale :<\/h3>\n<p><\/p>\n<p>Deckenventilator mit Vortex-Effekt ohne Fl\u00fcgel der Marke Exhale oder gleichwertig mit einem Luftdurchsatz von mindestens 6900 m3\/h und einer maximalen Leistung von 50 W.<\/p>\n<p><\/p>\n<p>Gem\u00e4\u00df der Norm NF EN IEC 60335-2-80 werden die Luftumw\u00e4lzer so installiert, dass der Abstand zwischen dem Boden und den Fl\u00fcgeln mindestens 2,30 m betr\u00e4gt.<\/p>\n<p><\/p>\n<p>Die Led-Lampe (optional) wird von folgendem Modell sein:<\/p>\n<p><\/p>\n<ul>\n<li>Option 1: kaltes Licht 5.500K (COOL) &#8211; 1200 lm<\/li>\n<li>Option 2: Warmes Licht 3.000K (WARM) &#8211; 1050 lm<\/li>\n<\/ul>\n<p><\/p>\n<p>Verkaufspreis inkl. MwSt. (20 % MwSt.) ohne LED*: XXX \u20ac<\/p>\n<p><\/p>\n<p>Verkaufspreis inkl. MwSt. (20 % MwSt.) mit LED*: YYY \u20ac<\/p>\n<p>[\/et_pb_text][et_pb_text ul_position=&#8221;inside&#8221; ul_item_indent=&#8221;25px&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; header_3_font=&#8221;|600|||||||&#8221; header_3_font_size=&#8221;20px&#8221; header_3_line_height=&#8221;1.7em&#8221; header_4_font=&#8221;|600|||||||&#8221; custom_padding=&#8221;20px|20px|20px|20px|true|true&#8221; border_width_all=&#8221;1px&#8221; global_colors_info=&#8221;{%22gcid-70ff693f-6f97-4074-be90-9adb196c4afe%22:%91%22header_3_text_color%22,%22header_3_text_color%22,%22header_3_text_color%22,%22header_3_text_color%22,%22header_3_text_color%22,%22header_3_text_color%22%93}&#8221;]<\/p>\n<h3>Samarat :<\/h3>\n<p><\/p>\n<p>Luftumw\u00e4lzer mit Schaufeln, Marke Samarat oder gleichwertig, mit einem Luftdurchsatz von mindestens 11893 m3\/h und einer maximalen Leistung von 43W.<\/p>\n<p><\/p>\n<p>Gem\u00e4\u00df der Norm NF EN IEC 60335-2-80 werden Luftumw\u00e4lzer so installiert, dass der Abstand zwischen dem Boden und den Schaufeln mindestens 2,30 m betr\u00e4gt.<\/p>\n<p><\/p>\n<p>Die Led-Lampe (optional) wird von folgendem Modell sein:<\/p>\n<p><\/p>\n<ul>\n<li>kaltes oder warmes Licht &#8211; 1500 lm<\/li>\n<\/ul>\n<p><\/p>\n<p>Verkaufspreis inkl. MwSt. (20 % MwSt.) ohne LEDs*: XXX \u20ac<\/p>\n<p><\/p>\n<p>Verkaufspreis inkl. MwSt. (20%) mit LED*: XXX \u20ac.<\/p>\n<p>[\/et_pb_text][et_pb_text ul_item_indent=&#8221;25px&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; header_3_font=&#8221;||||||||&#8221; header_3_text_color=&#8221;gcid-70ff693f-6f97-4074-be90-9adb196c4afe&#8221; header_3_font_size=&#8221;20px&#8221; header_3_line_height=&#8221;1.7em&#8221; header_4_font=&#8221;|600|||||||&#8221; global_colors_info=&#8221;{%22gcid-70ff693f-6f97-4074-be90-9adb196c4afe%22:%91%22header_3_text_color%22,%22header_3_text_color%22,%22header_3_text_color%22,%22header_3_text_color%22%93}&#8221;]<\/p>\n<p><em>* F\u00fcr Preise, fragen Sie uns<\/em><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text ul_item_indent=&#8221;25px&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;|600||on|||||&#8221; header_2_text_color=&#8221;gcid-93af2058-a512-4f99-b20c-ff5335d6c808&#8243; custom_margin=&#8221;||10px||false|false&#8221; custom_padding=&#8221;||||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-93af2058-a512-4f99-b20c-ff5335d6c808%22:%91%22header_2_text_color%22%93}&#8221;]<\/p>\n<h2>Reagieren Sie, befragen Sie unsere Experten!<\/h2>\n<p>[\/et_pb_text][et_pb_contact_form use_spam_service=&#8221;on&#8221; recaptcha_list=&#8221;brasseurs-air-re2020com Divi|brasseurs-air-re2020com Divi-0&#8243; email=&#8221;contact@brasseurs-air-re2020.com,crm-brasseurs@outlook.fr&#8221; custom_message=&#8221;brasseurs-air-re2020 : Blog &#8211; RE2020 en maison individuelle travaux r\u00e9serv\u00e9s au client quels points de vigilance. ALLEMAND||et_pb_line_break_holder||||et_pb_line_break_holder||Nom : %%last_Name%%||et_pb_line_break_holder||Pr\u00e9nom : %%first_Name%%||et_pb_line_break_holder||Email : %%email%%||et_pb_line_break_holder||T\u00e9l\u00e9phone : %%telephone%%||et_pb_line_break_holder||Code postal : %%postal%%||et_pb_line_break_holder||Ville : %%ville%%||et_pb_line_break_holder||Message : %%message%%&#8221; submit_button_text=&#8221;Senden&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; _unique_id=&#8221;9a009659-e65c-49fb-b268-76f136d04240&#8243; form_field_custom_margin=&#8221;0px||15px||false|false&#8221; form_field_custom_padding=&#8221;13px||13px||true|false&#8221; form_field_font_size=&#8221;14px&#8221; form_field_line_height=&#8221;1em&#8221; custom_button=&#8221;on&#8221; button_text_color=&#8221;#ffffff&#8221; button_bg_color=&#8221;gcid-93af2058-a512-4f99-b20c-ff5335d6c808&#8243; button_custom_margin=&#8221;20px||||false|false&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;||||false|false&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{%22gcid-93af2058-a512-4f99-b20c-ff5335d6c808%22:%91%22button_bg_color%22%93}&#8221; sticky_enabled=&#8221;0&#8243;][et_pb_contact_field field_id=&#8221;last_Name&#8221; field_title=&#8221;Name&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;first_Name&#8221; field_title=&#8221;Vorname&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;email&#8221; field_title=&#8221;Email Adresse&#8221; field_type=&#8221;email&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;telephone&#8221; field_title=&#8221;Telefonnummer&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;postal&#8221; field_title=&#8221;Postleitzahl&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;ville&#8221; field_title=&#8221;Stadt&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;message&#8221; field_title=&#8221;Ihre Nachricht&#8221; field_type=&#8221;text&#8221; fullwidth_field=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][\/et_pb_contact_form][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Vertrag \u00fcber den Bau eines Einfamilienhauses unterliegt einem besonderen Rahmen, der den Verbraucher sch\u00fctzt.<br \/>\nDer im Vertrag genannte Preis f\u00fcr das zu errichtende Haus besteht zwingend aus den Kosten des Geb\u00e4udes, die der Summe des vereinbarten Preises und gegebenenfalls den Kosten der Arbeiten, deren Ausf\u00fchrung sich der Bauherr vorbeh\u00e4lt, entsprechen&#8230;<\/p>\n","protected":false},"author":1,"featured_media":8815,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[45,48],"tags":[],"class_list":["post-8818","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-de","category-blog-de-maisons-individuelles"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>RE2020 im Einfamilienhaus: Arbeiten, die dem Kunden vorbehalten sind, worauf ist zu achten? - Brasseurs Air RE2020<\/title>\n<meta name=\"description\" content=\"Die Arbeiten, die in dem Merkblatt, das dem Vertrag \u00fcber den Bau eines Einfamilienhauses beigef\u00fcgt ist, reserviert werden, m\u00fcssen sehr genau beziffert werden.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.brasseurs-air-re2020.com\/de\/re2020-im-einfamilienhaus-arbeiten-die-dem-kunden-vorbehalten-sind-worauf-ist-zu-achten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RE2020 im Einfamilienhaus: Arbeiten, die dem Kunden vorbehalten sind, worauf ist zu achten? - Brasseurs Air RE2020\" \/>\n<meta property=\"og:description\" content=\"Die Arbeiten, die in dem Merkblatt, das dem Vertrag \u00fcber den Bau eines Einfamilienhauses beigef\u00fcgt ist, reserviert werden, m\u00fcssen sehr genau beziffert werden.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.brasseurs-air-re2020.com\/de\/re2020-im-einfamilienhaus-arbeiten-die-dem-kunden-vorbehalten-sind-worauf-ist-zu-achten\/\" \/>\n<meta property=\"og:site_name\" content=\"Brasseurs Air RE2020\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-17T14:35:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-13T20:55:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.brasseurs-air-re2020.com\/wp-content\/uploads\/2021\/12\/re2020-maison-individuelle-travaux-client-vigilance-02.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"654\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Brasseurs Air RE2020\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Brasseurs Air RE2020\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"17\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.brasseurs-air-re2020.com\/de\/re2020-im-einfamilienhaus-arbeiten-die-dem-kunden-vorbehalten-sind-worauf-ist-zu-achten\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.brasseurs-air-re2020.com\/de\/re2020-im-einfamilienhaus-arbeiten-die-dem-kunden-vorbehalten-sind-worauf-ist-zu-achten\/\"},\"author\":{\"name\":\"Brasseurs Air RE2020\",\"@id\":\"https:\/\/www.brasseurs-air-re2020.com\/de\/#\/schema\/person\/fa0536b41d60da8652200ecf81f8490a\"},\"headline\":\"RE2020 im Einfamilienhaus: Arbeiten, die dem Kunden vorbehalten sind, worauf ist zu achten?\",\"datePublished\":\"2021-12-17T14:35:19+00:00\",\"dateModified\":\"2026-07-13T20:55:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.brasseurs-air-re2020.com\/de\/re2020-im-einfamilienhaus-arbeiten-die-dem-kunden-vorbehalten-sind-worauf-ist-zu-achten\/\"},\"wordCount\":3485,\"publisher\":{\"@id\":\"https:\/\/www.brasseurs-air-re2020.com\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.brasseurs-air-re2020.com\/de\/re2020-im-einfamilienhaus-arbeiten-die-dem-kunden-vorbehalten-sind-worauf-ist-zu-achten\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.brasseurs-air-re2020.com\/wp-content\/uploads\/2021\/12\/re2020-maison-individuelle-travaux-client-vigilance-02.jpg\",\"articleSection\":[\"Blog DE\",\"Blog DE maisons individuelles\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.brasseurs-air-re2020.com\/de\/re2020-im-einfamilienhaus-arbeiten-die-dem-kunden-vorbehalten-sind-worauf-ist-zu-achten\/\",\"url\":\"https:\/\/www.brasseurs-air-re2020.com\/de\/re2020-im-einfamilienhaus-arbeiten-die-dem-kunden-vorbehalten-sind-worauf-ist-zu-achten\/\",\"name\":\"RE2020 im Einfamilienhaus: Arbeiten, die dem Kunden vorbehalten sind, worauf ist zu achten? - Brasseurs Air RE2020\",\"isPartOf\":{\"@id\":\"https:\/\/www.brasseurs-air-re2020.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.brasseurs-air-re2020.com\/de\/re2020-im-einfamilienhaus-arbeiten-die-dem-kunden-vorbehalten-sind-worauf-ist-zu-achten\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.brasseurs-air-re2020.com\/de\/re2020-im-einfamilienhaus-arbeiten-die-dem-kunden-vorbehalten-sind-worauf-ist-zu-achten\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.brasseurs-air-re2020.com\/wp-content\/uploads\/2021\/12\/re2020-maison-individuelle-travaux-client-vigilance-02.jpg\",\"datePublished\":\"2021-12-17T14:35:19+00:00\",\"dateModified\":\"2026-07-13T20:55:14+00:00\",\"description\":\"Die Arbeiten, die in dem Merkblatt, das dem Vertrag \u00fcber den Bau eines Einfamilienhauses beigef\u00fcgt ist, reserviert werden, m\u00fcssen sehr genau beziffert werden.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.brasseurs-air-re2020.com\/de\/re2020-im-einfamilienhaus-arbeiten-die-dem-kunden-vorbehalten-sind-worauf-ist-zu-achten\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.brasseurs-air-re2020.com\/de\/re2020-im-einfamilienhaus-arbeiten-die-dem-kunden-vorbehalten-sind-worauf-ist-zu-achten\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.brasseurs-air-re2020.com\/de\/re2020-im-einfamilienhaus-arbeiten-die-dem-kunden-vorbehalten-sind-worauf-ist-zu-achten\/#primaryimage\",\"url\":\"https:\/\/www.brasseurs-air-re2020.com\/wp-content\/uploads\/2021\/12\/re2020-maison-individuelle-travaux-client-vigilance-02.jpg\",\"contentUrl\":\"https:\/\/www.brasseurs-air-re2020.com\/wp-content\/uploads\/2021\/12\/re2020-maison-individuelle-travaux-client-vigilance-02.jpg\",\"width\":1100,\"height\":654},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.brasseurs-air-re2020.com\/de\/re2020-im-einfamilienhaus-arbeiten-die-dem-kunden-vorbehalten-sind-worauf-ist-zu-achten\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Deckenventilatoren\",\"item\":\"https:\/\/www.brasseurs-air-re2020.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog DE\",\"item\":\"https:\/\/www.brasseurs-air-re2020.com\/de\/category\/blog-de\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"RE2020 im Einfamilienhaus: Arbeiten, die dem Kunden vorbehalten sind, worauf ist zu achten?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.brasseurs-air-re2020.com\/de\/#website\",\"url\":\"https:\/\/www.brasseurs-air-re2020.com\/de\/\",\"name\":\"Brasseurs Air RE2020\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.brasseurs-air-re2020.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.brasseurs-air-re2020.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.brasseurs-air-re2020.com\/de\/#organization\",\"name\":\"Brasseurs d'air RE2020\",\"url\":\"https:\/\/www.brasseurs-air-re2020.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.brasseurs-air-re2020.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.brasseurs-air-re2020.com\/wp-content\/uploads\/2021\/12\/logo-brasseur-air-re-2020-new-01.png\",\"contentUrl\":\"https:\/\/www.brasseurs-air-re2020.com\/wp-content\/uploads\/2021\/12\/logo-brasseur-air-re-2020-new-01.png\",\"width\":200,\"height\":50,\"caption\":\"Brasseurs d'air RE2020\"},\"image\":{\"@id\":\"https:\/\/www.brasseurs-air-re2020.com\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/brasseurs-d-air-re2020\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.brasseurs-air-re2020.com\/de\/#\/schema\/person\/fa0536b41d60da8652200ecf81f8490a\",\"name\":\"Brasseurs Air RE2020\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.brasseurs-air-re2020.com\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0cc57458f76be9103b5365114139e2adbf54aafca10f9e65ff2db8ec5e0108b2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0cc57458f76be9103b5365114139e2adbf54aafca10f9e65ff2db8ec5e0108b2?s=96&d=mm&r=g\",\"caption\":\"Brasseurs Air RE2020\"},\"sameAs\":[\"http:\/\/www.brasseurs-air-re2020.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RE2020 im Einfamilienhaus: Arbeiten, die dem Kunden vorbehalten sind, worauf ist zu achten? - Brasseurs Air RE2020","description":"Die Arbeiten, die in dem Merkblatt, das dem Vertrag \u00fcber den Bau eines Einfamilienhauses beigef\u00fcgt ist, reserviert werden, m\u00fcssen sehr genau beziffert werden.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.brasseurs-air-re2020.com\/de\/re2020-im-einfamilienhaus-arbeiten-die-dem-kunden-vorbehalten-sind-worauf-ist-zu-achten\/","og_locale":"de_DE","og_type":"article","og_title":"RE2020 im Einfamilienhaus: Arbeiten, die dem Kunden vorbehalten sind, worauf ist zu achten? - Brasseurs Air RE2020","og_description":"Die Arbeiten, die in dem Merkblatt, das dem Vertrag \u00fcber den Bau eines Einfamilienhauses beigef\u00fcgt ist, reserviert werden, m\u00fcssen sehr genau beziffert werden.","og_url":"https:\/\/www.brasseurs-air-re2020.com\/de\/re2020-im-einfamilienhaus-arbeiten-die-dem-kunden-vorbehalten-sind-worauf-ist-zu-achten\/","og_site_name":"Brasseurs Air RE2020","article_published_time":"2021-12-17T14:35:19+00:00","article_modified_time":"2026-07-13T20:55:14+00:00","og_image":[{"width":1100,"height":654,"url":"https:\/\/www.brasseurs-air-re2020.com\/wp-content\/uploads\/2021\/12\/re2020-maison-individuelle-travaux-client-vigilance-02.jpg","type":"image\/jpeg"}],"author":"Brasseurs Air RE2020","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Brasseurs Air RE2020","Gesch\u00e4tzte Lesezeit":"17\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.brasseurs-air-re2020.com\/de\/re2020-im-einfamilienhaus-arbeiten-die-dem-kunden-vorbehalten-sind-worauf-ist-zu-achten\/#article","isPartOf":{"@id":"https:\/\/www.brasseurs-air-re2020.com\/de\/re2020-im-einfamilienhaus-arbeiten-die-dem-kunden-vorbehalten-sind-worauf-ist-zu-achten\/"},"author":{"name":"Brasseurs Air RE2020","@id":"https:\/\/www.brasseurs-air-re2020.com\/de\/#\/schema\/person\/fa0536b41d60da8652200ecf81f8490a"},"headline":"RE2020 im Einfamilienhaus: Arbeiten, die dem Kunden vorbehalten sind, worauf ist zu achten?","datePublished":"2021-12-17T14:35:19+00:00","dateModified":"2026-07-13T20:55:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.brasseurs-air-re2020.com\/de\/re2020-im-einfamilienhaus-arbeiten-die-dem-kunden-vorbehalten-sind-worauf-ist-zu-achten\/"},"wordCount":3485,"publisher":{"@id":"https:\/\/www.brasseurs-air-re2020.com\/de\/#organization"},"image":{"@id":"https:\/\/www.brasseurs-air-re2020.com\/de\/re2020-im-einfamilienhaus-arbeiten-die-dem-kunden-vorbehalten-sind-worauf-ist-zu-achten\/#primaryimage"},"thumbnailUrl":"https:\/\/www.brasseurs-air-re2020.com\/wp-content\/uploads\/2021\/12\/re2020-maison-individuelle-travaux-client-vigilance-02.jpg","articleSection":["Blog DE","Blog DE maisons individuelles"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.brasseurs-air-re2020.com\/de\/re2020-im-einfamilienhaus-arbeiten-die-dem-kunden-vorbehalten-sind-worauf-ist-zu-achten\/","url":"https:\/\/www.brasseurs-air-re2020.com\/de\/re2020-im-einfamilienhaus-arbeiten-die-dem-kunden-vorbehalten-sind-worauf-ist-zu-achten\/","name":"RE2020 im Einfamilienhaus: Arbeiten, die dem Kunden vorbehalten sind, worauf ist zu achten? - Brasseurs Air RE2020","isPartOf":{"@id":"https:\/\/www.brasseurs-air-re2020.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.brasseurs-air-re2020.com\/de\/re2020-im-einfamilienhaus-arbeiten-die-dem-kunden-vorbehalten-sind-worauf-ist-zu-achten\/#primaryimage"},"image":{"@id":"https:\/\/www.brasseurs-air-re2020.com\/de\/re2020-im-einfamilienhaus-arbeiten-die-dem-kunden-vorbehalten-sind-worauf-ist-zu-achten\/#primaryimage"},"thumbnailUrl":"https:\/\/www.brasseurs-air-re2020.com\/wp-content\/uploads\/2021\/12\/re2020-maison-individuelle-travaux-client-vigilance-02.jpg","datePublished":"2021-12-17T14:35:19+00:00","dateModified":"2026-07-13T20:55:14+00:00","description":"Die Arbeiten, die in dem Merkblatt, das dem Vertrag \u00fcber den Bau eines Einfamilienhauses beigef\u00fcgt ist, reserviert werden, m\u00fcssen sehr genau beziffert werden.","breadcrumb":{"@id":"https:\/\/www.brasseurs-air-re2020.com\/de\/re2020-im-einfamilienhaus-arbeiten-die-dem-kunden-vorbehalten-sind-worauf-ist-zu-achten\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.brasseurs-air-re2020.com\/de\/re2020-im-einfamilienhaus-arbeiten-die-dem-kunden-vorbehalten-sind-worauf-ist-zu-achten\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.brasseurs-air-re2020.com\/de\/re2020-im-einfamilienhaus-arbeiten-die-dem-kunden-vorbehalten-sind-worauf-ist-zu-achten\/#primaryimage","url":"https:\/\/www.brasseurs-air-re2020.com\/wp-content\/uploads\/2021\/12\/re2020-maison-individuelle-travaux-client-vigilance-02.jpg","contentUrl":"https:\/\/www.brasseurs-air-re2020.com\/wp-content\/uploads\/2021\/12\/re2020-maison-individuelle-travaux-client-vigilance-02.jpg","width":1100,"height":654},{"@type":"BreadcrumbList","@id":"https:\/\/www.brasseurs-air-re2020.com\/de\/re2020-im-einfamilienhaus-arbeiten-die-dem-kunden-vorbehalten-sind-worauf-ist-zu-achten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Deckenventilatoren","item":"https:\/\/www.brasseurs-air-re2020.com\/de\/"},{"@type":"ListItem","position":2,"name":"Blog DE","item":"https:\/\/www.brasseurs-air-re2020.com\/de\/category\/blog-de\/"},{"@type":"ListItem","position":3,"name":"RE2020 im Einfamilienhaus: Arbeiten, die dem Kunden vorbehalten sind, worauf ist zu achten?"}]},{"@type":"WebSite","@id":"https:\/\/www.brasseurs-air-re2020.com\/de\/#website","url":"https:\/\/www.brasseurs-air-re2020.com\/de\/","name":"Brasseurs Air RE2020","description":"","publisher":{"@id":"https:\/\/www.brasseurs-air-re2020.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.brasseurs-air-re2020.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.brasseurs-air-re2020.com\/de\/#organization","name":"Brasseurs d'air RE2020","url":"https:\/\/www.brasseurs-air-re2020.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.brasseurs-air-re2020.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.brasseurs-air-re2020.com\/wp-content\/uploads\/2021\/12\/logo-brasseur-air-re-2020-new-01.png","contentUrl":"https:\/\/www.brasseurs-air-re2020.com\/wp-content\/uploads\/2021\/12\/logo-brasseur-air-re-2020-new-01.png","width":200,"height":50,"caption":"Brasseurs d'air RE2020"},"image":{"@id":"https:\/\/www.brasseurs-air-re2020.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/brasseurs-d-air-re2020\/"]},{"@type":"Person","@id":"https:\/\/www.brasseurs-air-re2020.com\/de\/#\/schema\/person\/fa0536b41d60da8652200ecf81f8490a","name":"Brasseurs Air RE2020","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.brasseurs-air-re2020.com\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0cc57458f76be9103b5365114139e2adbf54aafca10f9e65ff2db8ec5e0108b2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0cc57458f76be9103b5365114139e2adbf54aafca10f9e65ff2db8ec5e0108b2?s=96&d=mm&r=g","caption":"Brasseurs Air RE2020"},"sameAs":["http:\/\/www.brasseurs-air-re2020.com"]}]}},"_links":{"self":[{"href":"https:\/\/www.brasseurs-air-re2020.com\/de\/wp-json\/wp\/v2\/posts\/8818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brasseurs-air-re2020.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brasseurs-air-re2020.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brasseurs-air-re2020.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brasseurs-air-re2020.com\/de\/wp-json\/wp\/v2\/comments?post=8818"}],"version-history":[{"count":4,"href":"https:\/\/www.brasseurs-air-re2020.com\/de\/wp-json\/wp\/v2\/posts\/8818\/revisions"}],"predecessor-version":[{"id":21855,"href":"https:\/\/www.brasseurs-air-re2020.com\/de\/wp-json\/wp\/v2\/posts\/8818\/revisions\/21855"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brasseurs-air-re2020.com\/de\/wp-json\/wp\/v2\/media\/8815"}],"wp:attachment":[{"href":"https:\/\/www.brasseurs-air-re2020.com\/de\/wp-json\/wp\/v2\/media?parent=8818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brasseurs-air-re2020.com\/de\/wp-json\/wp\/v2\/categories?post=8818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brasseurs-air-re2020.com\/de\/wp-json\/wp\/v2\/tags?post=8818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}