{"id":16009,"date":"2025-11-11T21:00:47","date_gmt":"2025-11-11T20:00:47","guid":{"rendered":"https:\/\/www.brasseurs-air-re2020.com\/despliegue-de-ventiladores-de-techo-en-residencias-de-mayores-una-solucion-para-enfrentar-las-futuras-olas-de-calor\/"},"modified":"2026-01-16T16:57:56","modified_gmt":"2026-01-16T15:57:56","slug":"despliegue-de-ventiladores-de-techo-en-residencias-de-mayores-una-solucion-para-enfrentar-las-futuras-olas-de-calor","status":"publish","type":"post","link":"https:\/\/www.brasseurs-air-re2020.com\/es\/despliegue-de-ventiladores-de-techo-en-residencias-de-mayores-una-solucion-para-enfrentar-las-futuras-olas-de-calor\/","title":{"rendered":"Despliegue de ventiladores de techo en residencias de mayores: \u00bfuna soluci\u00f3n para enfrentar las futuras olas de calor?"},"content":{"rendered":"<div class=\"pdfprnt-buttons pdfprnt-buttons-post pdfprnt-top-right\"><a href=\"javascript: imageToPdf()\" class=\"pdfprnt-button pdfprnt-button-pdf\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.brasseurs-air-re2020.com\/wp-content\/plugins\/pdf-print\/images\/pdf.png\" alt=\"image_pdf\" title=\"Ver PDF\" \/><span class=\"pdfprnt-button-title pdfprnt-button-pdf-title\">T\u00e9l\u00e9charger l\u2019article en PDF<\/span><\/a><\/div><p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text ul_item_indent=&#8221;25px&#8221; disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_4_font_size=&#8221;16px&#8221; header_4_line_height=&#8221;1.4em&#8221; background_color=&#8221;#d4f0fc&#8221; custom_padding=&#8221;20px|20px|20px|20px|true|true&#8221; box_shadow_style=&#8221;preset2&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Aunque el recuerdo del verano de 2003 y sus 19.000 muertes sigue presente en la memoria colectiva, la regularidad, la intensidad y la duraci\u00f3n de las olas de calor muestran que ya no se trata de un evento puntual.<\/p>\n<p>De hecho, 2003 asoci\u00f3 dolorosamente la edad avanzada con la mortalidad.<\/p>\n<p>Por fortuna, los \u00faltimos a\u00f1os muestran que en las residencias de ancianos, las lecciones aprendidas del pasado han llevado a una situaci\u00f3n que parece estar m\u00e1s controlada<a href=\"#_edn1\" name=\"_ednref1\"><span>[i]<\/span><\/a>.<\/p>\n<p>No obstante, todav\u00eda queda mucho por hacer para que las temporadas estivales sean, tanto para el personal como para los residentes, estaciones como cualquier otra.<\/p>\n<p>En este art\u00edculo, dirigido tanto a <strong>dise\u00f1adores de edificios<\/strong> como a <strong>directores de instituciones que acogen a personas mayores<\/strong>, proponemos hacer un diagn\u00f3stico tanto normativo como t\u00e9cnico, para que todos los actores involucrados puedan actuar de manera eficaz sobre los factores que contribuyen al confort veraniego.<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/www.brasseurs-air-re2020.com\/wp-content\/uploads\/2025\/11\/vagues-de-chaleur-observees-01.jpg&#8221; alt=&#8221;Olas de calor observadas y ola de calor&#8221; title_text=&#8221;vagues-de-chaleur-observees-01&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||10px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text ul_item_indent=&#8221;25px&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;|600|||||||&#8221; header_2_text_color=&#8221;gcid-70ff693f-6f97-4074-be90-9adb196c4afe&#8221; header_3_font=&#8221;|600|||||||&#8221; header_3_text_color=&#8221;gcid-70ff693f-6f97-4074-be90-9adb196c4afe&#8221; header_4_font=&#8221;|600|||||||&#8221; custom_margin=&#8221;||15px||false|false&#8221; custom_padding=&#8221;||0px|||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-70ff693f-6f97-4074-be90-9adb196c4afe%22:%91%22header_3_text_color%22,%22header_3_text_color%22,%22header_2_text_color%22%93}&#8221;]<em>Figura 1: Olas de calor observadas desde 1947 en la Francia metropolitana \u2013 fuente M\u00e9t\u00e9o France<\/em>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row module_id=&#8221;re2020-carbone&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text ul_item_indent=&#8221;25px&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;|600|||||||&#8221; header_2_text_color=&#8221;gcid-70ff693f-6f97-4074-be90-9adb196c4afe&#8221; header_3_font=&#8221;|600|||||||&#8221; header_3_text_color=&#8221;gcid-70ff693f-6f97-4074-be90-9adb196c4afe&#8221; header_4_font=&#8221;|600|||||||&#8221; custom_margin=&#8221;||15px||false|false&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{%22gcid-70ff693f-6f97-4074-be90-9adb196c4afe%22:%91%22header_3_text_color%22,%22header_3_text_color%22,%22header_2_text_color%22%93}&#8221;]<\/p>\n<h2>Refrigeraci\u00f3n y ventilaci\u00f3n: aclarando los t\u00e9rminos<\/h2>\n<p><\/p>\n<p>En el mundo de los despachos de estudios y de los arquitectos, la distinci\u00f3n es bastante clara: la refrigeraci\u00f3n se asocia exclusivamente a los sistemas de aire acondicionado, mientras que la ventilaci\u00f3n a menudo se extiende a los ventiladores de techo, que generan una sensaci\u00f3n de temperatura m\u00e1s fresca.<\/p>\n<p><\/p>\n<p>Sin embargo, los textos relativos a la \u00abventilaci\u00f3n\u00bb en los establecimientos que alojan personas mayores asocian este concepto a la \u00abproducci\u00f3n de fr\u00edo\u00bb.<\/p>\n<p><\/p>\n<p>En el resto de esta publicaci\u00f3n, y para disponer de t\u00e9rminos expl\u00edcitos, abordaremos las tres situaciones posibles:<\/p>\n<p><\/p>\n<ul>\n<li>Aire acondicionado<\/li>\n<li>Ventilaci\u00f3n (ventiladores de techo)<\/li>\n<li>Ventilaci\u00f3n h\u00edbrida, que corresponde a la combinaci\u00f3n de aire acondicionado y ventiladores de techo<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row module_id=&#8221;ic-construction&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text ul_item_indent=&#8221;25px&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;|600|||||||&#8221; header_2_text_color=&#8221;gcid-70ff693f-6f97-4074-be90-9adb196c4afe&#8221; header_3_font=&#8221;|600|||||||&#8221; header_3_text_color=&#8221;gcid-70ff693f-6f97-4074-be90-9adb196c4afe&#8221; header_4_font=&#8221;|600|||||||&#8221; custom_margin=&#8221;||15px||false|false&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{%22gcid-70ff693f-6f97-4074-be90-9adb196c4afe%22:%91%22header_3_text_color%22,%22header_3_text_color%22,%22header_2_text_color%22%93}&#8221;]<\/p>\n<h2>Olas de calor y preservaci\u00f3n de la salud en residencias de ancianos: \u00bfqu\u00e9 acciones concretas?<\/h2>\n<p>Los textos regulatorios publicados entre 2004 y 2005 dieron lugar a una nueva exigencia: la puesta a disposici\u00f3n de una <strong>habitaci\u00f3n climatizada<\/strong>, accesible para los residentes con movilidad reducida y capaz de acoger a una <strong>proporci\u00f3n significativa de los residentes<\/strong>.<\/p>\n<p>Estos son los textos:<\/p>\n<ul>\n<li>Decreto n.\u00ba 2005-768 del 7 de julio de 2005<a href=\"#_edn2\" name=\"_ednref2\"><span>[ii]<\/span><\/a>: impone a los establecimientos que alojan personas mayores la creaci\u00f3n de un espacio o habitaci\u00f3n equipada con un sistema fijo de aire acondicionado.<\/li>\n<li>Orden del 7 de julio de 2005 &amp; Orden del 8 de agosto de 2005<a href=\"#_edn3\" name=\"_ednref3\"><span>[iii]<\/span><\/a>: establecen el pliego de condiciones del \u00abplan azul\u00bb (plan de organizaci\u00f3n en caso de crisis sanitaria o clim\u00e1tica) y las condiciones de instalaci\u00f3n de un sistema de aire acondicionado o de puesta a disposici\u00f3n de una habitaci\u00f3n climatizada.<\/li>\n<\/ul>\n<p>La \u00abproporci\u00f3n significativa de residentes\u00bb sigue siendo bastante ambigua. Se deja a la valoraci\u00f3n de los responsables del establecimiento. En la pr\u00e1ctica, suele ser el comedor el refugio en caso de altas temperaturas.<\/p>\n<p>Sin embargo, esto plantea un problema pr\u00e1ctico para algunos residentes fr\u00e1giles, cuyo estado de salud no siempre permite abandonar su habitaci\u00f3n. Por ello, deben permanecer en su habitaci\u00f3n, que a menudo no est\u00e1 climatizada y cuya temperatura puede alcanzar niveles elevados.<\/p>\n<p>Se aplican otras medidas (formaci\u00f3n del personal, plan azul, alertas meteorol\u00f3gicas, etc.), pero aqu\u00ed nos centraremos en los aspectos t\u00e9rmicos.<\/p>\n<p>Las soluciones que mejoran el confort t\u00e9rmico de verano son financiadas por la Caisse Nationale de Solidarit\u00e9 pour l&#8217;Autonomie<a href=\"#_edn4\" name=\"_ednref4\"><span>[iv]<\/span><\/a> (CNSA). Estas incluyen una amplia gama de medidas que limitan la exposici\u00f3n al calor y favorecen la ventilaci\u00f3n natural. Con frecuencia incluyen ventiladores de techo, como se observa en la regi\u00f3n <a href=\"https:\/\/www.centre-val-de-loire.ars.sante.fr\/media\/82289\/download?inline=&amp;utm_source=chatgpt.com\" target=\"_blank\" rel=\"noopener\">Centre-Val de Loire<\/a> y <a href=\"https:\/\/www.bourgogne-franche-comte.ars.sante.fr\/media\/118831\/download?inline=&amp;utm_source=chatgpt.com\" target=\"_blank\" rel=\"noopener\">Bourgogne Franche-Comt\u00e9<\/a>\u2026<\/p>\n<p>Recordemos en esta ocasi\u00f3n diferentes soluciones para el confort de verano: brise-soleil, aislamiento de techos y paredes, filtros solares exteriores, persianas, sobreventilaci\u00f3n nocturna, etc.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row module_id=&#8221;ic-construction&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text ul_item_indent=&#8221;25px&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;|600|||||||&#8221; header_2_text_color=&#8221;gcid-70ff693f-6f97-4074-be90-9adb196c4afe&#8221; header_3_font=&#8221;|600|||||||&#8221; header_3_text_color=&#8221;gcid-70ff693f-6f97-4074-be90-9adb196c4afe&#8221; header_4_font=&#8221;|600|||||||&#8221; custom_margin=&#8221;||15px||false|false&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{%22gcid-70ff693f-6f97-4074-be90-9adb196c4afe%22:%91%22header_3_text_color%22,%22header_3_text_color%22,%22header_2_text_color%22%93}&#8221;]<\/p>\n<h2>RE2020, establecimientos de salud y residencias de mayores: \u00bfpronto habr\u00e1 cambios en las nuevas construcciones?<\/h2>\n<p><\/p>\n<p>La normativa RE2020 se ampliar\u00e1 a partir del 1 de enero de 2026 a ciertos edificios terciarios que hasta ahora estaban sujetos a la RT2012:<\/p>\n<p><\/p>\n<ul>\n<li>Hoteles,<\/li>\n<li>Restaurantes,<\/li>\n<li>Comercios,<\/li>\n<li>Centros de atenci\u00f3n a la primera infancia (guarder\u00edas, jardines de infancia),<\/li>\n<li>Edificios universitarios,<\/li>\n<li>Mediatecas y bibliotecas,<\/li>\n<li><strong>Establecimientos de salud (consultorios m\u00e9dicos, hospitales, etc.) y residencias de mayores (EHPAD),<\/strong><\/li>\n<li>Gimnasios, salas deportivas y vestuarios,<\/li>\n<li>Edificios de uso industrial y artesanal,<\/li>\n<li>Terminales aeroportuarias.<\/li>\n<\/ul>\n<p><\/p>\n<p>Los proyectos de decreto fueron sometidos a consulta p\u00fablica<a href=\"#_edn5\" name=\"_ednref5\">[v]<\/a>, la cual se cerr\u00f3 en junio de 2025.<\/p>\n<p><\/p>\n<p>De este modo, en las nuevas residencias de mayores, el confort t\u00e9rmico en verano ser\u00e1 mucho mejor considerado, con la introducci\u00f3n del indicador <strong>DH (grados-hora)<\/strong>, que busca evitar el sobrecalentamiento mediante un mejor dise\u00f1o arquitect\u00f3nico.<\/p>\n<p><\/p>\n<p>En las habitaciones, la RE2020 establece el objetivo de <strong>garantizar el confort de verano sin recurrir sistem\u00e1ticamente a la climatizaci\u00f3n.<\/strong><\/p>\n<p><\/p>\n<p>Esta podr\u00e1 instalarse \u00fanicamente en las <strong>situaciones en las que las normas de higiene o seguridad impidan abrir las ventanas hacia el exterior<\/strong> (pacientes fr\u00e1giles, por ejemplo). Pero en el resto de los espacios, <strong>los ventiladores de techo<\/strong> podr\u00e1n ocupar plenamente su lugar.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row module_id=&#8221;ic-energie&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text ul_item_indent=&#8221;25px&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;|600|||||||&#8221; header_2_text_color=&#8221;gcid-70ff693f-6f97-4074-be90-9adb196c4afe&#8221; header_3_font=&#8221;|600|||||||&#8221; header_3_text_color=&#8221;gcid-70ff693f-6f97-4074-be90-9adb196c4afe&#8221; header_4_font=&#8221;|600|||||||&#8221; custom_margin=&#8221;||15px||false|false&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{%22gcid-70ff693f-6f97-4074-be90-9adb196c4afe%22:%91%22header_3_text_color%22,%22header_3_text_color%22,%22header_2_text_color%22%93}&#8221;]<\/p>\n<h2>Refrigeraci\u00f3n h\u00edbrida: cuando la climatizaci\u00f3n y los ventiladores de techo se combinan para ofrecer lo mejor<\/h2>\n<p><\/p>\n<p>La implantaci\u00f3n masiva de sistemas de climatizaci\u00f3n en las residencias de mayores se enfrenta a varios obst\u00e1culos.<\/p>\n<p><\/p>\n<p>En primer lugar, desde un punto de vista puramente econ\u00f3mico, las instalaciones de producci\u00f3n de fr\u00edo son costosas tanto en la fase de inversi\u00f3n (construcci\u00f3n o renovaci\u00f3n) como en la de explotaci\u00f3n (consumo el\u00e9ctrico).<\/p>\n<p><\/p>\n<p>Adem\u00e1s, contribuyen a la formaci\u00f3n de <strong>islas de calor<\/strong>, ya que expulsan aire caliente al exterior.<\/p>\n<p><\/p>\n<p>Por \u00faltimo, los gases refrigerantes que utilizan tienen un <strong>impacto devastador sobre el medio ambiente<\/strong>.<\/p>\n<p><\/p>\n<p>Un enfoque inteligente consiste, por un lado, en <strong>limitar su n\u00famero<\/strong> y, por otro, en <strong>asociar los sistemas de climatizaci\u00f3n restantes con ventiladores de techo<\/strong>. As\u00ed, un estudio realizado por la Universidad de Berkeley<a href=\"#_edn6\" name=\"_ednref6\">[vi]<\/a> en edificios terciarios mostr\u00f3 <strong>ahorros energ\u00e9ticos del 30 %<\/strong> gracias a la combinaci\u00f3n de climatizaci\u00f3n y ventiladores de techo.<\/p>\n<p><\/p>\n<p>En este esquema, la <strong>temperatura de consigna<\/strong> para la refrigeraci\u00f3n se incrementa deliberadamente en algunos grados. Este ligero aumento <strong>no afecta al confort t\u00e9rmico percibido<\/strong>, ya que el ventilador de techo genera una sensaci\u00f3n de frescor equivalente.<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/www.brasseurs-air-re2020.com\/wp-content\/uploads\/2025\/11\/ehpad-neuf-rafraichissement-hybride-01.jpg&#8221; alt=&#8221;Refrigeraci\u00f3n h\u00edbrida&#8221; title_text=&#8221;ehpad-neuf-rafraichissement-hybride-01&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||10px||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row module_id=&#8221;ic-energie&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text ul_item_indent=&#8221;25px&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;|600|||||||&#8221; header_2_text_color=&#8221;gcid-70ff693f-6f97-4074-be90-9adb196c4afe&#8221; header_3_font=&#8221;|600|||||||&#8221; header_3_text_color=&#8221;gcid-70ff693f-6f97-4074-be90-9adb196c4afe&#8221; header_4_font=&#8221;|600|||||||&#8221; custom_margin=&#8221;||15px||false|false&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{%22gcid-70ff693f-6f97-4074-be90-9adb196c4afe%22:%91%22header_3_text_color%22,%22header_3_text_color%22,%22header_2_text_color%22%93}&#8221;]<\/p>\n<h2>Experiencias concretas<\/h2>\n<p><\/p>\n<p>En dos residencias de Voiron, la instalaci\u00f3n de ventiladores de techo en las habitaciones cambi\u00f3 notablemente la percepci\u00f3n t\u00e9rmica de los ocupantes.<\/p>\n<p><\/p>\n<p>Antes de la instalaci\u00f3n, el 100 % del grupo encuestado consideraba que la temperatura durante los periodos m\u00e1s calurosos era insoportable y afectaba su actividad f\u00edsica.<\/p>\n<p><\/p>\n<p>Despu\u00e9s de la instalaci\u00f3n, el 60 % de las personas encuestadas consider\u00f3 que la situaci\u00f3n se hab\u00eda vuelto soportable o incluso totalmente confortable. El 78 % estim\u00f3 que el ventilador de techo era discreto o muy discreto en t\u00e9rminos de ruido, y el <strong>79 % afirm\u00f3 que las ventajas del ventilador superaban ampliamente los inconvenientes.<\/strong><\/p>\n<p><\/p>\n<p><strong>Otros testimonios de responsables de residencias respaldan estas observaciones:<\/strong><\/p>\n<p><\/p>\n<ul>\n<li><u>Directora de la residencia Bellevue en Decazeville<\/u>: <em>los ventiladores de techo han mejorado significativamente nuestro confort tanto en verano como en invierno, y tambi\u00e9n han resuelto nuestro problema de baja altura de techo gracias a su reducido grosor.<\/em><\/li>\n<li><u>Director de la residencia de mayores Les S\u00e9nioriales (Cannes)<\/u>: <em>Estos equipos son perfectamente adecuados para los espacios ocupados por personas mayores, ya que el ventilador instalado difunde el aire horizontalmente en 360 grados. El aire se desliza a lo largo del techo, evitando la sensaci\u00f3n de corrientes fr\u00edas directas sobre los ocupantes. Estos aprecian especialmente su funcionamiento silencioso y discreto (sin efecto estrobosc\u00f3pico respecto a los puntos de luz).<\/em><\/li>\n<\/ul>\n<p><\/p>\n<p>De manera destacable, los <strong>ventiladores de techo sin aspas con efecto Vortex de la marca Exhale<\/strong> son muy valorados en los espacios que acogen a personas mayores. En efecto, generan un flujo de aire suave y distribuido de forma homog\u00e9nea por toda la habitaci\u00f3n, lo que se adapta muy bien a las necesidades de los residentes.<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/www.brasseurs-air-re2020.com\/wp-content\/uploads\/2025\/11\/2.-Ehpad-neuf.jpg&#8221; alt=&#8221;Refrigeraci\u00f3n h\u00edbrida&#8221; title_text=&#8221;2. Ehpad neuf&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||10px||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text ul_item_indent=&#8221;25px&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;|600|||||||&#8221; header_2_text_color=&#8221;gcid-70ff693f-6f97-4074-be90-9adb196c4afe&#8221; header_3_font=&#8221;|600|||||||&#8221; header_3_text_color=&#8221;gcid-70ff693f-6f97-4074-be90-9adb196c4afe&#8221; header_4_font=&#8221;|600|||||||&#8221; custom_margin=&#8221;||15px||false|false&#8221; custom_padding=&#8221;||0px|||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-70ff693f-6f97-4074-be90-9adb196c4afe%22:%91%22header_3_text_color%22,%22header_3_text_color%22,%22header_2_text_color%22%93}&#8221;]<\/p>\n<p><em>Extracto de un art\u00edculo de Dauphin\u00e9 Lib\u00e9r\u00e9 que menciona el ventilador de techo Exhale<a href=\"#_edn7\" name=\"_ednref7\"><span>[vii]<\/span><\/a><\/em><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row module_id=&#8221;ic-energie&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text ul_item_indent=&#8221;25px&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;|600|||||||&#8221; header_2_text_color=&#8221;gcid-70ff693f-6f97-4074-be90-9adb196c4afe&#8221; header_3_font=&#8221;|600|||||||&#8221; header_3_text_color=&#8221;gcid-70ff693f-6f97-4074-be90-9adb196c4afe&#8221; header_4_font=&#8221;|600|||||||&#8221; custom_margin=&#8221;||15px||false|false&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{%22gcid-70ff693f-6f97-4074-be90-9adb196c4afe%22:%91%22header_3_text_color%22,%22header_3_text_color%22,%22header_2_text_color%22%93}&#8221;]<\/p>\n<h2>\u00bfCu\u00e1les son los l\u00edmites del beneficio de los ventiladores de techo en los EHPAD?<\/h2>\n<p><\/p>\n<p><strong>Lograr con los ventiladores de techo una ganancia de temperatura percibida de 3 a 4\u00b0C<\/strong> en las habitaciones es, evidentemente, algo excelente, que por supuesto se ver\u00e1 reforzado por una mejora de la envolvente del edificio.<\/p>\n<p><\/p>\n<p>Hay que a\u00f1adir que los ventiladores de techo siguen siendo eficaces en un amplio rango de temperaturas. Una publicaci\u00f3n de la Universidad de Berkeley<a href=\"#_edn8\" name=\"_ednref8\">[viii]<\/a> (diferente de la anterior) muestra, de hecho, que <strong>mejoran la percepci\u00f3n t\u00e9rmica hasta los 43\u00b0C<\/strong>. Lo ideal, por supuesto, es mantenerse por debajo de 28\u00b0C, pero esto pone de manifiesto claramente el margen de maniobra de esta soluci\u00f3n.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row module_id=&#8221;ic-energie&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text ul_item_indent=&#8221;25px&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;|600|||||||&#8221; header_2_text_color=&#8221;gcid-70ff693f-6f97-4074-be90-9adb196c4afe&#8221; header_3_font=&#8221;|600|||||||&#8221; header_3_text_color=&#8221;gcid-70ff693f-6f97-4074-be90-9adb196c4afe&#8221; header_4_font=&#8221;|600|||||||&#8221; custom_margin=&#8221;||15px||false|false&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{%22gcid-70ff693f-6f97-4074-be90-9adb196c4afe%22:%91%22header_3_text_color%22,%22header_3_text_color%22,%22header_2_text_color%22%93}&#8221;]<\/p>\n<h2>\u00bfC\u00f3mo pasar a la acci\u00f3n?<\/h2>\n<p><\/p>\n<p>Para las instituciones que acogen a p\u00fablicos vulnerables, las compras o inversiones en material ligero son bastante accesibles: aires acondicionados, ventiladores de techo, parasoles, pel\u00edculas protectoras, cortinas&#8230;<\/p>\n<p><\/p>\n<p>Por su parte, los planes de ayuda a la inversi\u00f3n inmobiliaria financiados por la CNSA est\u00e1n reservados a grandes operaciones de renovaci\u00f3n o construcci\u00f3n (\u2265 800 k\u20ac desde 2022). Estos planes incluyen autom\u00e1ticamente criterios de rendimiento energ\u00e9tico.<\/p>\n<p><\/p>\n<p>La consideraci\u00f3n del confort de verano tambi\u00e9n puede apoyarse en los Consejeros y Coordinadores Regionales en Transici\u00f3n Energ\u00e9tica y Ecol\u00f3gica en Salud (CTEES), que est\u00e1n presentes en las ARS. Como menciona la CNSA, \u00abdesde 2022, m\u00e1s de 5200 establecimientos, de los cuales 3600 del sector m\u00e9dico-social, ya han sido acompa\u00f1ados por m\u00e1s de 150 CTEES para diagn\u00f3sticos y seguimientos\u00bb<a href=\"#_edn9\" name=\"_ednref9\"><span>[ix]<\/span><\/a>.<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/www.brasseurs-air-re2020.com\/wp-content\/uploads\/2025\/11\/passer-a-l-action-ehpad-canicule-ventilateur-01.jpg&#8221; alt=&#8221;\u00bfC\u00f3mo pasar a la acci\u00f3n?&#8221; title_text=&#8221;passer-a-l-action-ehpad-canicule-ventilateur-01&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||10px||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text ul_item_indent=&#8221;25px&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;|600|||||||&#8221; header_2_text_color=&#8221;gcid-70ff693f-6f97-4074-be90-9adb196c4afe&#8221; header_3_font=&#8221;|600|||||||&#8221; header_3_text_color=&#8221;gcid-70ff693f-6f97-4074-be90-9adb196c4afe&#8221; header_4_font=&#8221;|600|||||||&#8221; custom_margin=&#8221;||15px||false|false&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{%22gcid-70ff693f-6f97-4074-be90-9adb196c4afe%22:%91%22header_3_text_color%22,%22header_3_text_color%22,%22header_2_text_color%22%93}&#8221;]<\/p>\n<p>El objetivo es tener en cuenta el confort t\u00e9rmico de verano desde la fase de dise\u00f1o o renovaci\u00f3n de los establecimientos que alojan o reciben a personas vulnerables. Estos CTEES permitir\u00e1n, en particular, realizar auditor\u00edas energ\u00e9ticas dentro de los centros sanitarios y sociosanitarios e iniciar planes de acci\u00f3n para reducir el consumo energ\u00e9tico y mejorar la calidad del aire.<\/p>\n<p>Tambi\u00e9n es importante destacar la <strong>plataforma especial de la ANAP<\/strong><a href=\"#_edn10\" name=\"_ednref10\"><span>[x]<\/span><\/a>, la Agencia Nacional de Desempe\u00f1o Sanitario y Sociosanitario, que est\u00e1 <strong>expresamente dedicada a las subvenciones para proyectos ecol\u00f3gicos<\/strong>. Desde el enlace anterior, basta con hacer clic en \u00abiniciar\u00bb y luego elegir \u00abadaptaci\u00f3n al cambio clim\u00e1tico\u00bb para acceder a la lista de financiamientos disponibles.<\/p>\n<p>Adem\u00e1s, los responsables de los establecimientos pueden ponerse en contacto con los despachos de ingenier\u00eda cualificados OPQIBI de su regi\u00f3n, capacitados para realizar auditor\u00edas energ\u00e9ticas<a href=\"#_edn11\" name=\"_ednref11\"><span>[xi]<\/span><\/a>.<\/p>\n<p>Esto es a\u00fan m\u00e1s relevante hoy en d\u00eda, con el <strong>\u00abdecreto terciario\u00bb<\/strong> que impone una fuerte reducci\u00f3n del consumo energ\u00e9tico en los edificios terciarios de m\u00e1s de 1000 m\u00b2, ya que es posible realizar una <strong>auditor\u00eda energ\u00e9tica global<\/strong> que tenga en cuenta espec\u00edficamente el <strong>sobrecalentamiento estival<\/strong>. Adem\u00e1s, las auditor\u00edas incluyen la evaluaci\u00f3n de los recursos financieros disponibles, como los certificados de ahorro energ\u00e9tico (CEE).<\/p>\n<p>Apoy\u00e1ndose en este an\u00e1lisis energ\u00e9tico, tambi\u00e9n es importante se\u00f1alar la existencia de un nuevo <strong>referencial dedicado al confort de verano en los edificios: H\u00e9olem<\/strong>, que, hasta donde sabemos, es la \u00fanica iniciativa <strong>totalmente centrada en esta tem\u00e1tica<\/strong>, aunque existen otros sellos que abordan todas las caracter\u00edsticas de los edificios<a href=\"#_edn12\" name=\"_ednref12\"><span>[xii]<\/span><\/a>.<\/p>\n<p>Bas\u00e1ndose en estos diferentes elementos, los responsables de los establecimientos que acogen a nuestros mayores, as\u00ed como los dise\u00f1adores, estar\u00e1n en posici\u00f3n de actuar sobre bases s\u00f3lidas.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row module_id=&#8221;ic-energie&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text ul_item_indent=&#8221;25px&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;|600|||||||&#8221; header_2_text_color=&#8221;gcid-70ff693f-6f97-4074-be90-9adb196c4afe&#8221; header_3_font=&#8221;|600|||||||&#8221; header_3_text_color=&#8221;gcid-70ff693f-6f97-4074-be90-9adb196c4afe&#8221; header_4_font=&#8221;|600|||||||&#8221; custom_margin=&#8221;||15px||false|false&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{%22gcid-70ff693f-6f97-4074-be90-9adb196c4afe%22:%91%22header_3_text_color%22,%22header_3_text_color%22,%22header_2_text_color%22%93}&#8221;]<\/p>\n<h2>Agradecimientos<\/h2>\n<p><\/p>\n<p><em>Por toda la informaci\u00f3n proporcionada previamente, as\u00ed como por su trabajo de revisi\u00f3n minuciosa y correcciones de este art\u00edculo, agradecemos a Murielle Blondeau, Manager de Transici\u00f3n especializada en la Direcci\u00f3n de establecimientos sociosanitarios y <\/em><a href=\"https:\/\/www.serenalliance.com\/\" target=\"_blank\" rel=\"noopener\"><em>Directora de SERENALLIANCE<\/em><\/a><em>.<\/em><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text ul_item_indent=&#8221;25px&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_3_font=&#8221;|600|||||||&#8221; header_3_text_color=&#8221;gcid-70ff693f-6f97-4074-be90-9adb196c4afe&#8221; header_4_font=&#8221;|600|||||||&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{%22gcid-70ff693f-6f97-4074-be90-9adb196c4afe%22:%91%22header_3_text_color%22%93}&#8221;]<\/p>\n<p><a href=\"#_ednref1\" name=\"_edn1\"><span>[i]<\/span><\/a> En 2025, a pesar de dos episodios de ola de calor, Sant\u00e9 Publique France evalu\u00f3 en 760 el n\u00famero de muertes excesivas durante el verano: ver <a href=\"https:\/\/www.santepubliquefrance.fr\/content\/download\/739261\/4741467?version=1\" target=\"_blank\" rel=\"noopener\">https:\/\/www.santepubliquefrance.fr\/content\/download\/739261\/4741467?version=1<\/a> y <a href=\"https:\/\/www.santepubliquefrance.fr\/determinants-de-sante\/climat\/fortes-chaleurs-canicule\/documents\/bulletin-national\/canicule-et-sante-exces-de-mortalite.-bulletin-du-11-septembre-2025\" target=\"_blank\" rel=\"noopener\">https:\/\/www.santepubliquefrance.fr\/determinants-de-sante\/climat\/fortes-chaleurs-canicule\/documents\/bulletin-national\/canicule-et-sante-exces-de-mortalite.-bulletin-du-11-septembre-2025<\/a><\/p>\n<p><a href=\"#_ednref2\" name=\"_edn2\"><span>[ii]<\/span><\/a> Decreto del 7 de julio de 2005: <a href=\"https:\/\/www.legifrance.gouv.fr\/loda\/id\/JORFTEXT000000259713\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.legifrance.gouv.fr\/loda\/id\/JORFTEXT000000259713\/<\/a><\/p>\n<p><a href=\"#_ednref3\" name=\"_edn3\"><span>[iii]<\/span><\/a> Orden del 7 de julio de 2005: <a href=\"https:\/\/www.legifrance.gouv.fr\/loda\/id\/JORFTEXT000000633683\" target=\"_blank\" rel=\"noopener\">https:\/\/www.legifrance.gouv.fr\/loda\/id\/JORFTEXT000000633683<\/a><br \/>Orden del 8 de agosto de 2005: <a href=\"https:\/\/www.legifrance.gouv.fr\/loda\/id\/LEGIARTI000030238866\/2005-08-19\" target=\"_blank\" rel=\"noopener\">https:\/\/www.legifrance.gouv.fr\/loda\/id\/LEGIARTI000030238866\/2005-08-19<\/a><\/p>\n<p><a href=\"#_ednref4\" name=\"_edn4\"><span>[iv]<\/span><\/a> Soci\u00e9t\u00e9 Fran\u00e7aise de M\u00e9decine d\u2019Urgence &#8211; LA COUR DES COMPTES SE INTERROGA SOBRE LA RESILIENCIA DE LOS ESTABLECIMIENTOS SANITARIOS Y SOCIOSANITARIOS FRENTE A LAS OLAS DE CALOR &#8211; <a href=\"https:\/\/www.sfmu.org\/fr\/actualites\/actualites-de-l-urgences\/la-cour-des-comptes-s-interroge-sur-la-resilience-des-etablissements-sanitaires-et-medico-sociaux-face-aux-vagues-de-chaleur\/new_id\/69723?\" target=\"_blank\" rel=\"noopener\">https:\/\/www.sfmu.org\/fr\/actualites\/actualites-de-l-urgences\/la-cour-des-comptes-s-interroge-sur-la-resilience-des-etablissements-sanitaires-et-medico-sociaux-face-aux-vagues-de-chaleur\/new_id\/69723?<\/a><\/p>\n<p><a href=\"#_ednref5\" name=\"_edn5\"><span>[v]<\/span><\/a> Accesible en Vie Publique: <a href=\"https:\/\/www.vie-publique.fr\/consultations\/298780-projet-de-decret-performance-energetique-constructions-de-batiments\" target=\"_blank\" rel=\"noopener\">https:\/\/www.vie-publique.fr\/consultations\/298780-projet-de-decret-performance-energetique-constructions-de-batiments<\/a><\/p>\n<p><a href=\"#_ednref6\" name=\"_edn6\"><span>[vi]<\/span><\/a> Ver art\u00edculo (en ingl\u00e9s): <a href=\"https:\/\/vcresearch.berkeley.edu\/news\/hybrid-cooling-leads-significant-energy-savings-tropical-office-buildings\" target=\"_blank\" rel=\"noopener\">https:\/\/vcresearch.berkeley.edu\/news\/hybrid-cooling-leads-significant-energy-savings-tropical-office-buildings<\/a><\/p>\n<p><a href=\"#_ednref7\" name=\"_edn7\"><span>[vii]<\/span><\/a> El art\u00edculo completo est\u00e1 disponible aqu\u00ed: https:\/\/www.ledauphine.com\/societe\/2024\/08\/18\/voiron-isere-canicule-apres-de-menus-travaux-un-ete-plus-serein-a-l-ehpad-voironnais<\/p>\n<p><a href=\"#_ednref8\" name=\"_edn8\"><span>[viii]<\/span><\/a> Un resumen en ingl\u00e9s est\u00e1 disponible aqu\u00ed: <a href=\"https:\/\/www.linkedin.com\/pulse\/when-fans-safe-harmful-during-extreme-heat-stefano-schiavon-udfqc\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.linkedin.com\/pulse\/when-fans-safe-harmful-during-extreme-heat-stefano-schiavon-udfqc\/<\/a> &#8211; la versi\u00f3n completa est\u00e1 disponible en ScienceDirect: <a href=\"https:\/\/www.sciencedirect.com\/science\/article\/pii\/S0360132325007413?via%3Dihub\" target=\"_blank\" rel=\"noopener\">https:\/\/www.sciencedirect.com\/science\/article\/pii\/S0360132325007413?via%3Dihub<\/a><\/p>\n<p><a href=\"#_ednref9\" name=\"_edn9\"><span>[ix]<\/span><\/a> Publicaci\u00f3n disponible aqu\u00ed: <a href=\"https:\/\/www.cnsa.fr\/actualites\/plan-daide-linvestissement-2023-un-bilan-positif?\" target=\"_blank\" rel=\"noopener\">https:\/\/www.cnsa.fr\/actualites\/plan-daide-linvestissement-2023-un-bilan-positif?<\/a><\/p>\n<p><a href=\"#_ednref10\" name=\"_edn10\"><span>[x]<\/span><\/a> Plataforma de subvenciones ecol\u00f3gicas de la ANAP: <a href=\"https:\/\/www.anap.fr\/s\/financer-sa-transition-ecologique\" target=\"_blank\" rel=\"noopener\">https:\/\/www.anap.fr\/s\/financer-sa-transition-ecologique<\/a>. Desde el enlace, solo hay que hacer clic en &#8220;d\u00e9marrer&#8221; y luego elegir &#8220;adaptaci\u00f3n al cambio clim\u00e1tico&#8221; para acceder a la lista de financiamientos disponibles.<\/p>\n<p><a href=\"#_ednref11\" name=\"_edn11\"><span>[xi]<\/span><\/a> Solo hay que ingresar la direcci\u00f3n <a href=\"https:\/\/www.opqibi.com\/recherche-plus\" target=\"_blank\" rel=\"noopener\">https:\/\/www.opqibi.com\/recherche-plus<\/a>, indicar Regi\u00f3n o Departamento, y escribir el c\u00f3digo &#8220;1905&#8221; correspondiente a la auditor\u00eda energ\u00e9tica terciaria.<\/p>\n<p><a href=\"#_ednref12\" name=\"_edn12\"><span>[xii]<\/span><\/a> Muchos otros sellos ambientales permiten mejorar los edificios, tanto en obra nueva como en renovaci\u00f3n, teniendo tambi\u00e9n en cuenta el confort de verano. Entre ellos se pueden citar HQE, los enfoques B\u00e2timents Durables, BREEAM\u2026<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row module_id=&#8221;ic-energie&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221; locked=&#8221;off&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text ul_item_indent=&#8221;25px&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;|600|||||||&#8221; header_2_text_color=&#8221;gcid-70ff693f-6f97-4074-be90-9adb196c4afe&#8221; header_3_font=&#8221;|600|||||||&#8221; header_3_text_color=&#8221;gcid-70ff693f-6f97-4074-be90-9adb196c4afe&#8221; header_4_font=&#8221;|600|||||||&#8221; custom_margin=&#8221;||15px||false|false&#8221; custom_padding=&#8221;||0px|||&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{%22gcid-70ff693f-6f97-4074-be90-9adb196c4afe%22:%91%22header_3_text_color%22,%22header_3_text_color%22,%22header_2_text_color%22%93}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h2>Encuentra a continuaci\u00f3n el contenido del art\u00edculo en nuestro canal de YouTube<\/h2>\n<p>[\/et_pb_text][et_pb_video src=&#8221;https:\/\/www.youtube.com\/watch?v=A3cwg6GtqS0&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;][\/et_pb_video][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En este art\u00edculo, dirigido tanto a los dise\u00f1adores de edificios como a los responsables de residencias de personas mayores, proponemos realizar un balance tanto normativo como t\u00e9cnico, de manera que todos los actores implicados puedan actuar de forma eficaz sobre los factores que contribuyen al confort veraniego.<\/p>\n","protected":false},"author":1,"featured_media":15994,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[122],"tags":[],"class_list":["post-16009","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-esp"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Despliegue de ventiladores de techo en residencias de mayores: \u00bfuna soluci\u00f3n para enfrentar las futuras olas de calor? - Brasseurs Air RE2020<\/title>\n<meta name=\"description\" content=\"Los ventiladores de techo en residencias de ancianos: una soluci\u00f3n eficaz y duradera para mejorar el confort veraniego frente a las futuras olas de calor.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.brasseurs-air-re2020.com\/es\/despliegue-de-ventiladores-de-techo-en-residencias-de-mayores-una-solucion-para-enfrentar-las-futuras-olas-de-calor\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Despliegue de ventiladores de techo en residencias de mayores: \u00bfuna soluci\u00f3n para enfrentar las futuras olas de calor? - Brasseurs Air RE2020\" \/>\n<meta property=\"og:description\" content=\"Los ventiladores de techo en residencias de ancianos: una soluci\u00f3n eficaz y duradera para mejorar el confort veraniego frente a las futuras olas de calor.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.brasseurs-air-re2020.com\/es\/despliegue-de-ventiladores-de-techo-en-residencias-de-mayores-una-solucion-para-enfrentar-las-futuras-olas-de-calor\/\" \/>\n<meta property=\"og:site_name\" content=\"Brasseurs Air RE2020\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-11T20:00:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-16T15:57:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.brasseurs-air-re2020.com\/wp-content\/uploads\/2025\/11\/canicule-sante-ehpad-02.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Brasseurs Air RE2020\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Brasseurs Air RE2020\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"20 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.brasseurs-air-re2020.com\/es\/despliegue-de-ventiladores-de-techo-en-residencias-de-mayores-una-solucion-para-enfrentar-las-futuras-olas-de-calor\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.brasseurs-air-re2020.com\/es\/despliegue-de-ventiladores-de-techo-en-residencias-de-mayores-una-solucion-para-enfrentar-las-futuras-olas-de-calor\/\"},\"author\":{\"name\":\"Brasseurs Air RE2020\",\"@id\":\"https:\/\/www.brasseurs-air-re2020.com\/es\/#\/schema\/person\/fa0536b41d60da8652200ecf81f8490a\"},\"headline\":\"Despliegue de ventiladores de techo en residencias de mayores: \u00bfuna soluci\u00f3n para enfrentar las futuras olas de calor?\",\"datePublished\":\"2025-11-11T20:00:47+00:00\",\"dateModified\":\"2026-01-16T15:57:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.brasseurs-air-re2020.com\/es\/despliegue-de-ventiladores-de-techo-en-residencias-de-mayores-una-solucion-para-enfrentar-las-futuras-olas-de-calor\/\"},\"wordCount\":4028,\"publisher\":{\"@id\":\"https:\/\/www.brasseurs-air-re2020.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.brasseurs-air-re2020.com\/es\/despliegue-de-ventiladores-de-techo-en-residencias-de-mayores-una-solucion-para-enfrentar-las-futuras-olas-de-calor\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.brasseurs-air-re2020.com\/wp-content\/uploads\/2025\/11\/canicule-sante-ehpad-02.jpg\",\"articleSection\":[\"Blog ESP\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.brasseurs-air-re2020.com\/es\/despliegue-de-ventiladores-de-techo-en-residencias-de-mayores-una-solucion-para-enfrentar-las-futuras-olas-de-calor\/\",\"url\":\"https:\/\/www.brasseurs-air-re2020.com\/es\/despliegue-de-ventiladores-de-techo-en-residencias-de-mayores-una-solucion-para-enfrentar-las-futuras-olas-de-calor\/\",\"name\":\"Despliegue de ventiladores de techo en residencias de mayores: \u00bfuna soluci\u00f3n para enfrentar las futuras olas de calor? - Brasseurs Air RE2020\",\"isPartOf\":{\"@id\":\"https:\/\/www.brasseurs-air-re2020.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.brasseurs-air-re2020.com\/es\/despliegue-de-ventiladores-de-techo-en-residencias-de-mayores-una-solucion-para-enfrentar-las-futuras-olas-de-calor\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.brasseurs-air-re2020.com\/es\/despliegue-de-ventiladores-de-techo-en-residencias-de-mayores-una-solucion-para-enfrentar-las-futuras-olas-de-calor\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.brasseurs-air-re2020.com\/wp-content\/uploads\/2025\/11\/canicule-sante-ehpad-02.jpg\",\"datePublished\":\"2025-11-11T20:00:47+00:00\",\"dateModified\":\"2026-01-16T15:57:56+00:00\",\"description\":\"Los ventiladores de techo en residencias de ancianos: una soluci\u00f3n eficaz y duradera para mejorar el confort veraniego frente a las futuras olas de calor.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.brasseurs-air-re2020.com\/es\/despliegue-de-ventiladores-de-techo-en-residencias-de-mayores-una-solucion-para-enfrentar-las-futuras-olas-de-calor\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.brasseurs-air-re2020.com\/es\/despliegue-de-ventiladores-de-techo-en-residencias-de-mayores-una-solucion-para-enfrentar-las-futuras-olas-de-calor\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.brasseurs-air-re2020.com\/es\/despliegue-de-ventiladores-de-techo-en-residencias-de-mayores-una-solucion-para-enfrentar-las-futuras-olas-de-calor\/#primaryimage\",\"url\":\"https:\/\/www.brasseurs-air-re2020.com\/wp-content\/uploads\/2025\/11\/canicule-sante-ehpad-02.jpg\",\"contentUrl\":\"https:\/\/www.brasseurs-air-re2020.com\/wp-content\/uploads\/2025\/11\/canicule-sante-ehpad-02.jpg\",\"width\":1000,\"height\":667,\"caption\":\"D\u00e9ploiement de ventilateurs de plafond dans les EHPAD : une solution pour faire face aux futures canicules ?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.brasseurs-air-re2020.com\/es\/despliegue-de-ventiladores-de-techo-en-residencias-de-mayores-una-solucion-para-enfrentar-las-futuras-olas-de-calor\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Brasseur d\u2019air\",\"item\":\"https:\/\/www.brasseurs-air-re2020.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog ESP\",\"item\":\"https:\/\/www.brasseurs-air-re2020.com\/es\/category\/blog-esp\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Despliegue de ventiladores de techo en residencias de mayores: \u00bfuna soluci\u00f3n para enfrentar las futuras olas de calor?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.brasseurs-air-re2020.com\/es\/#website\",\"url\":\"https:\/\/www.brasseurs-air-re2020.com\/es\/\",\"name\":\"Brasseurs Air RE2020\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.brasseurs-air-re2020.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.brasseurs-air-re2020.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.brasseurs-air-re2020.com\/es\/#organization\",\"name\":\"Brasseurs d'air RE2020\",\"url\":\"https:\/\/www.brasseurs-air-re2020.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.brasseurs-air-re2020.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.brasseurs-air-re2020.com\/wp-content\/uploads\/2021\/12\/logo-brasseur-air-re-2020-new-01.png\",\"contentUrl\":\"https:\/\/www.brasseurs-air-re2020.com\/wp-content\/uploads\/2021\/12\/logo-brasseur-air-re-2020-new-01.png\",\"width\":200,\"height\":50,\"caption\":\"Brasseurs d'air RE2020\"},\"image\":{\"@id\":\"https:\/\/www.brasseurs-air-re2020.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/brasseurs-d-air-re2020\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.brasseurs-air-re2020.com\/es\/#\/schema\/person\/fa0536b41d60da8652200ecf81f8490a\",\"name\":\"Brasseurs Air RE2020\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.brasseurs-air-re2020.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0cc57458f76be9103b5365114139e2adbf54aafca10f9e65ff2db8ec5e0108b2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0cc57458f76be9103b5365114139e2adbf54aafca10f9e65ff2db8ec5e0108b2?s=96&d=mm&r=g\",\"caption\":\"Brasseurs Air RE2020\"},\"sameAs\":[\"http:\/\/www.brasseurs-air-re2020.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Despliegue de ventiladores de techo en residencias de mayores: \u00bfuna soluci\u00f3n para enfrentar las futuras olas de calor? - Brasseurs Air RE2020","description":"Los ventiladores de techo en residencias de ancianos: una soluci\u00f3n eficaz y duradera para mejorar el confort veraniego frente a las futuras olas de calor.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.brasseurs-air-re2020.com\/es\/despliegue-de-ventiladores-de-techo-en-residencias-de-mayores-una-solucion-para-enfrentar-las-futuras-olas-de-calor\/","og_locale":"es_ES","og_type":"article","og_title":"Despliegue de ventiladores de techo en residencias de mayores: \u00bfuna soluci\u00f3n para enfrentar las futuras olas de calor? - Brasseurs Air RE2020","og_description":"Los ventiladores de techo en residencias de ancianos: una soluci\u00f3n eficaz y duradera para mejorar el confort veraniego frente a las futuras olas de calor.","og_url":"https:\/\/www.brasseurs-air-re2020.com\/es\/despliegue-de-ventiladores-de-techo-en-residencias-de-mayores-una-solucion-para-enfrentar-las-futuras-olas-de-calor\/","og_site_name":"Brasseurs Air RE2020","article_published_time":"2025-11-11T20:00:47+00:00","article_modified_time":"2026-01-16T15:57:56+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/www.brasseurs-air-re2020.com\/wp-content\/uploads\/2025\/11\/canicule-sante-ehpad-02.jpg","type":"image\/jpeg"}],"author":"Brasseurs Air RE2020","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Brasseurs Air RE2020","Tiempo de lectura":"20 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.brasseurs-air-re2020.com\/es\/despliegue-de-ventiladores-de-techo-en-residencias-de-mayores-una-solucion-para-enfrentar-las-futuras-olas-de-calor\/#article","isPartOf":{"@id":"https:\/\/www.brasseurs-air-re2020.com\/es\/despliegue-de-ventiladores-de-techo-en-residencias-de-mayores-una-solucion-para-enfrentar-las-futuras-olas-de-calor\/"},"author":{"name":"Brasseurs Air RE2020","@id":"https:\/\/www.brasseurs-air-re2020.com\/es\/#\/schema\/person\/fa0536b41d60da8652200ecf81f8490a"},"headline":"Despliegue de ventiladores de techo en residencias de mayores: \u00bfuna soluci\u00f3n para enfrentar las futuras olas de calor?","datePublished":"2025-11-11T20:00:47+00:00","dateModified":"2026-01-16T15:57:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.brasseurs-air-re2020.com\/es\/despliegue-de-ventiladores-de-techo-en-residencias-de-mayores-una-solucion-para-enfrentar-las-futuras-olas-de-calor\/"},"wordCount":4028,"publisher":{"@id":"https:\/\/www.brasseurs-air-re2020.com\/es\/#organization"},"image":{"@id":"https:\/\/www.brasseurs-air-re2020.com\/es\/despliegue-de-ventiladores-de-techo-en-residencias-de-mayores-una-solucion-para-enfrentar-las-futuras-olas-de-calor\/#primaryimage"},"thumbnailUrl":"https:\/\/www.brasseurs-air-re2020.com\/wp-content\/uploads\/2025\/11\/canicule-sante-ehpad-02.jpg","articleSection":["Blog ESP"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.brasseurs-air-re2020.com\/es\/despliegue-de-ventiladores-de-techo-en-residencias-de-mayores-una-solucion-para-enfrentar-las-futuras-olas-de-calor\/","url":"https:\/\/www.brasseurs-air-re2020.com\/es\/despliegue-de-ventiladores-de-techo-en-residencias-de-mayores-una-solucion-para-enfrentar-las-futuras-olas-de-calor\/","name":"Despliegue de ventiladores de techo en residencias de mayores: \u00bfuna soluci\u00f3n para enfrentar las futuras olas de calor? - Brasseurs Air RE2020","isPartOf":{"@id":"https:\/\/www.brasseurs-air-re2020.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.brasseurs-air-re2020.com\/es\/despliegue-de-ventiladores-de-techo-en-residencias-de-mayores-una-solucion-para-enfrentar-las-futuras-olas-de-calor\/#primaryimage"},"image":{"@id":"https:\/\/www.brasseurs-air-re2020.com\/es\/despliegue-de-ventiladores-de-techo-en-residencias-de-mayores-una-solucion-para-enfrentar-las-futuras-olas-de-calor\/#primaryimage"},"thumbnailUrl":"https:\/\/www.brasseurs-air-re2020.com\/wp-content\/uploads\/2025\/11\/canicule-sante-ehpad-02.jpg","datePublished":"2025-11-11T20:00:47+00:00","dateModified":"2026-01-16T15:57:56+00:00","description":"Los ventiladores de techo en residencias de ancianos: una soluci\u00f3n eficaz y duradera para mejorar el confort veraniego frente a las futuras olas de calor.","breadcrumb":{"@id":"https:\/\/www.brasseurs-air-re2020.com\/es\/despliegue-de-ventiladores-de-techo-en-residencias-de-mayores-una-solucion-para-enfrentar-las-futuras-olas-de-calor\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.brasseurs-air-re2020.com\/es\/despliegue-de-ventiladores-de-techo-en-residencias-de-mayores-una-solucion-para-enfrentar-las-futuras-olas-de-calor\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.brasseurs-air-re2020.com\/es\/despliegue-de-ventiladores-de-techo-en-residencias-de-mayores-una-solucion-para-enfrentar-las-futuras-olas-de-calor\/#primaryimage","url":"https:\/\/www.brasseurs-air-re2020.com\/wp-content\/uploads\/2025\/11\/canicule-sante-ehpad-02.jpg","contentUrl":"https:\/\/www.brasseurs-air-re2020.com\/wp-content\/uploads\/2025\/11\/canicule-sante-ehpad-02.jpg","width":1000,"height":667,"caption":"D\u00e9ploiement de ventilateurs de plafond dans les EHPAD : une solution pour faire face aux futures canicules ?"},{"@type":"BreadcrumbList","@id":"https:\/\/www.brasseurs-air-re2020.com\/es\/despliegue-de-ventiladores-de-techo-en-residencias-de-mayores-una-solucion-para-enfrentar-las-futuras-olas-de-calor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Brasseur d\u2019air","item":"https:\/\/www.brasseurs-air-re2020.com\/es\/"},{"@type":"ListItem","position":2,"name":"Blog ESP","item":"https:\/\/www.brasseurs-air-re2020.com\/es\/category\/blog-esp\/"},{"@type":"ListItem","position":3,"name":"Despliegue de ventiladores de techo en residencias de mayores: \u00bfuna soluci\u00f3n para enfrentar las futuras olas de calor?"}]},{"@type":"WebSite","@id":"https:\/\/www.brasseurs-air-re2020.com\/es\/#website","url":"https:\/\/www.brasseurs-air-re2020.com\/es\/","name":"Brasseurs Air RE2020","description":"","publisher":{"@id":"https:\/\/www.brasseurs-air-re2020.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.brasseurs-air-re2020.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.brasseurs-air-re2020.com\/es\/#organization","name":"Brasseurs d'air RE2020","url":"https:\/\/www.brasseurs-air-re2020.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.brasseurs-air-re2020.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.brasseurs-air-re2020.com\/wp-content\/uploads\/2021\/12\/logo-brasseur-air-re-2020-new-01.png","contentUrl":"https:\/\/www.brasseurs-air-re2020.com\/wp-content\/uploads\/2021\/12\/logo-brasseur-air-re-2020-new-01.png","width":200,"height":50,"caption":"Brasseurs d'air RE2020"},"image":{"@id":"https:\/\/www.brasseurs-air-re2020.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/brasseurs-d-air-re2020\/"]},{"@type":"Person","@id":"https:\/\/www.brasseurs-air-re2020.com\/es\/#\/schema\/person\/fa0536b41d60da8652200ecf81f8490a","name":"Brasseurs Air RE2020","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.brasseurs-air-re2020.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0cc57458f76be9103b5365114139e2adbf54aafca10f9e65ff2db8ec5e0108b2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0cc57458f76be9103b5365114139e2adbf54aafca10f9e65ff2db8ec5e0108b2?s=96&d=mm&r=g","caption":"Brasseurs Air RE2020"},"sameAs":["http:\/\/www.brasseurs-air-re2020.com"]}]}},"_links":{"self":[{"href":"https:\/\/www.brasseurs-air-re2020.com\/es\/wp-json\/wp\/v2\/posts\/16009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brasseurs-air-re2020.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brasseurs-air-re2020.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brasseurs-air-re2020.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brasseurs-air-re2020.com\/es\/wp-json\/wp\/v2\/comments?post=16009"}],"version-history":[{"count":6,"href":"https:\/\/www.brasseurs-air-re2020.com\/es\/wp-json\/wp\/v2\/posts\/16009\/revisions"}],"predecessor-version":[{"id":16999,"href":"https:\/\/www.brasseurs-air-re2020.com\/es\/wp-json\/wp\/v2\/posts\/16009\/revisions\/16999"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brasseurs-air-re2020.com\/es\/wp-json\/wp\/v2\/media\/15994"}],"wp:attachment":[{"href":"https:\/\/www.brasseurs-air-re2020.com\/es\/wp-json\/wp\/v2\/media?parent=16009"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brasseurs-air-re2020.com\/es\/wp-json\/wp\/v2\/categories?post=16009"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brasseurs-air-re2020.com\/es\/wp-json\/wp\/v2\/tags?post=16009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}